{"id":31142,"date":"2021-07-02T06:00:40","date_gmt":"2021-07-01T21:00:40","guid":{"rendered":"https:\/\/hon.jp\/news\/?p=31142"},"modified":"2021-07-01T19:52:45","modified_gmt":"2021-07-01T10:52:45","slug":"%e6%97%a5%e5%88%8a%e5%87%ba%e7%89%88%e3%83%8b%e3%83%a5%e3%83%bc%e3%82%b9%e3%81%be%e3%81%a8%e3%82%81-2021-07-02","status":"publish","type":"post","link":"https:\/\/hon.jp\/news\/1.0\/0\/31142","title":{"rendered":"\u65e5\u520a\u51fa\u7248\u30cb\u30e5\u30fc\u30b9\u307e\u3068\u3081 2021.07.02"},"content":{"rendered":"<p>\u3000\u4f1d\u7d71\u7684\u306a\u53d6\u6b21\uff06\u66f8\u5e97\u6d41\u901a\u306e\u5546\u696d\u51fa\u7248\u304b\u3089\u3001\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u3092\u6d3b\u7528\u3057\u305f\u30c7\u30b8\u30bf\u30eb\u30d1\u30d6\u30ea\u30c3\u30b7\u30f3\u30b0\u307e\u3067\u3001\u5e83\u3044\u610f\u5473\u3067\u306e\u51fa\u7248\u306b\u95a2\u9023\u3059\u308b\u30cb\u30e5\u30fc\u30b9\u3092\u30c7\u30a4\u30ea\u30fc\u3067\u307e\u3068\u3081\u3066\u3044\u307e\u3059\u3002<br \/>\n<!--more--><\/p>\n<h3 class=\"selector3\">\u56fd\u5185<\/h3>\n<h4 class=\"selector4\">\u767d\u9ed2\u30de\u30f3\u30ac\u306f\u672a\u5b8c\u6210? \u30d4\u30af\u30b7\u30d6\u3068PFN\u304c\u30de\u30f3\u30ac\u306e\u30ab\u30e9\u30fc\u5316\u306b\u53d6\u308a\u7d44\u3080\u30ef\u30b1\u3008Impress Watch\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.watch.impress.co.jp\/docs\/topic\/1333132.html\" data-lkc-id=\"2997\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/d323bd4cb3b1d7c7d7b06ae30453b183d89189be207aba7732f92396e2306470.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u767d\u9ed2\u30de\u30f3\u30ac\u306f\u672a\u5b8c\u6210? \u30d4\u30af\u30b7\u30d6\u3068PFN\u304c\u30de\u30f3\u30ac\u306e\u30ab\u30e9\u30fc\u5316\u306b\u53d6\u308a\u7d44\u3080\u30ef\u30b1<\/div><div class=\"lkc-url\" title=\"https:\/\/www.watch.impress.co.jp\/docs\/topic\/1333132.html\">https:\/\/www.watch.impress.co.jp\/docs\/topic\/1333132.html<\/div><div class=\"lkc-excerpt\">\u30d4\u30af\u30b7\u30d6\u3068Preferred Networks(PFN)\u306f5\u670828\u65e5\u3001\u30de\u30f3\u30ac\u3092\u81ea\u52d5\u3067\u30ab\u30e9\u30fc\u5316\u3059\u308b\u30b5\u30fc\u30d3\u30b9\u300cPetalica Paint for Manga\u300d\u3092\u767a\u8868\u3001\u6cd5\u4eba\u5411\u3051\u306b\u8a66\u9a13\u63d0\u4f9b\u3092\u958b\u59cb\u3057\u305f\u3002\u4e21\u793e\u306b\u3088\u308b\u30de\u30f3\u30ac\u539f\u7a3f\u306e\u81ea\u52d5\u30ab\u30e9\u30fc\u5316\u30b5\u30fc\u30d3\u30b9\u306f\u3001\u3059\u3067\u306b\u63d0\u4f9b\u3055\u308c\u3066\u3044\u308b\u30a4\u30e9\u30b9\u30c8\u5411\u3051\u306b\u7d9a\u304f\u3082\u306e\u3067\u3001\u6ce8\u76ee\u3092\u96c6\u3081\u3066\u3044\u308b\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.watch.impress.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.watch.impress.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u7570\u8ad6\u3042\u308a\u3001\u30d5\u30a1\u30b9\u30c8\u6620\u753b\u8003\u2015\u2015\u902e\u6355\u306f\u60aa\u624b\u3067\u3042\u308b \/ \u7530\u4e2d\u8fb0\u96c4 \/ \u8a08\u91cf\u7d4c\u6e08\u5b66\u3008SYNODOS -\u30b7\u30ce\u30c9\u30b9-\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/synodos.jp\/culture\/24375\" data-lkc-id=\"2343\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/ab064272a200b9c6467791096ca2cad22cb45038ae6a043c1c0a6210673521b4.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">https:\/\/synodos.jp\/culture\/24375<\/div><div class=\"lkc-url\" title=\"https:\/\/synodos.jp\/culture\/24375\">https:\/\/synodos.jp\/culture\/24375<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=synodos.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">synodos.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30a8\u30f3\u30bf\u30e1\u8868\u73fe\u306e\u81ea\u7531\u3092\u653f\u7b56\u3067\u9078\u3076\u306a\u3089\u515a\u6d3e\u3067\u306f\u306a\u304f\u500b\u4eba\u3067\u3010\u90fd\u8b70\u90782021 \u5019\u88dc\u8005\u30a2\u30f3\u30b1\u30fc\u30c8\u7d50\u679c\u3064\u304d\u3011\u3008\u9078\u6319\u30c9\u30c3\u30c8\u30b3\u30e0\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/nordot.app\/783196643919626240?c=491375730748638305\" data-lkc-id=\"2998\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/efcfaa3d4ea81ad7f92fab51df8c02e9db330aab7ee0910a2c5d3958f25c84c7.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30a8\u30f3\u30bf\u30e1\u8868\u73fe\u306e\u81ea\u7531\u3092\u653f\u7b56\u3067\u9078\u3076\u306a\u3089\u515a\u6d3e\u3067\u306f\u306a\u304f\u500b\u4eba\u3067\u3010\u90fd\u8b70\u90782021 \u5019\u88dc\u8005\u30a2\u30f3\u30b1\u30fc\u30c8\u7d50\u679c\u3064\u304d\u3011 \uff5c \u9078\u6319\u30c9\u30c3\u30c8\u30b3\u30e0<\/div><div class=\"lkc-url\" title=\"https:\/\/nordot.app\/783196643919626240?c=491375730748638305\">https:\/\/nordot.app\/783196643919626240?c=491375730748638305<\/div><div class=\"lkc-excerpt\">\u25a0 \u306f\u3058\u3081\u306b\u30a8\u30f3\u30bf\u30fc\u30c6\u30a4\u30e1\u30f3\u30c8\u8868\u73fe\u306e\u81ea\u7531\u306e\u4f1a\uff08AFEE\uff09\u4ee3\u8868\u306e\u5742\u4e95\u5d07\u4fca\u3068\u7533\u3057\u307e\u3059\u3002\u73fe\u5728\u3001\u6771\u4eac\u90fd\u8b70\u4f1a\u8b70...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=nordot.app\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">nordot.app<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u805e\u3053\u3048\u59cb\u3081\u305fVoiceTech\u306e\u9f13\u52d5\u3008\u65e5\u7d4c\u30d3\u30b8\u30cd\u30b9\u96fb\u5b50\u7248\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/business.nikkei.com\/atcl\/gen\/19\/00324\/062800001\/\" data-lkc-id=\"2342\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/04255f059de7dd1ddb7047848514f9d90e7662ee4e9a041ae3a8ada330dd8ffb.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u805e\u3053\u3048\u59cb\u3081\u305fVoiceTech\u306e\u9f13\u52d5<\/div><div class=\"lkc-url\" title=\"https:\/\/business.nikkei.com\/atcl\/gen\/19\/00324\/062800001\/\">https:\/\/business.nikkei.com\/atcl\/gen\/19\/00324\/062800001\/<\/div><div class=\"lkc-excerpt\">\u7c73\u5927\u624bIT\u4f01\u696d\u304c\u305d\u308d\u3063\u3066\u6ce8\u76ee\u3057\u7d9a\u3051\u308b\u300cVoiceTech\uff08\u30dc\u30a4\u30b9\u30c6\u30c3\u30af\uff09\u300d\u3002\u4eba\u9593\u306e\u300c\u697d\u306b\u60c5\u5831\u3092\u5f97\u305f\u3044\u300d\u3068\u3044\u3046\u6b32\u6c42\u304c\u884c\u304d\u3064\u304f\u3001\u7a76\u6975\u306e\u5f62\u304c\u300c\u97f3\u58f0\u300d\u3060\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=business.nikkei.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">business.nikkei.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">radiko\u3001Podcast\u3001Clubhouse\u3001\u30b3\u30ed\u30ca\u798d\u3067\u6ce8\u76ee\u3055\u308c\u308b\u97f3\u58f0\u30e1\u30c7\u30a3\u30a2\u306e\u4fa1\u5024\u3068\u672a\u6765\u3008@DIME \u30a2\u30c3\u30c8\u30c0\u30a4\u30e0\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/dime.jp\/genre\/1155650\/\" data-lkc-id=\"2999\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/b437a2ac2989c9588fbcfb41488466c04d93bb660dcc60b8abac5a7908d5ef12.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">radiko\u3001Podcast\u3001Clubhouse\u3001\u30b3\u30ed\u30ca\u798d\u3067\u6ce8\u76ee\u3055\u308c\u308b\u97f3\u58f0\u30e1\u30c7\u30a3\u30a2\u306e\u4fa1\u5024\u3068\u672a\u6765\uff5c@DIME \u30a2\u30c3\u30c8\u30c0\u30a4\u30e0<\/div><div class=\"lkc-url\" title=\"https:\/\/dime.jp\/genre\/1155650\/\">https:\/\/dime.jp\/genre\/1155650\/<\/div><div class=\"lkc-excerpt\">radiko\u3001Podcast\u3001Clubhouse\u304c\u30d0\u30ba\u3063\u305f\u3053\u3068\u3067\u3001\u30c7\u30b8\u30bf\u30eb\u7cfb\u97f3\u58f0\u30e1\u30c7\u30a3\u30a2\u5168\u4f53\u306e\u6ce8\u76ee\u5ea6\u304c\u6025\u4e0a\u6607\u3057\u3066\u3044\u308b\u3002\u30b3\u30ed\u30ca\u798d\u3067\u3001\u3050\u3093\u3050\u3093\u6ce8\u76ee\u5ea6\u3092\u5897\u3059\u30c8\u30ec\u30f3\u30c9\u30e1\u30c7\u30a3\u30a2\u306e\u672a\u6765\u3068\u53ef\u80fd\u6027\u306b\u3064\u3044\u3066\u5c02\u9580\u5bb6\u306b\u8a71\u3092\u805e\u3044\u305f\u3002\u3008\u3053\u306e\u65b9...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=dime.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">dime.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30de\u30f3\u30ac\u696d\u754cNews\u307e\u3068\u3081 7\/1-001\u3008\u83ca\u6c60\u5065\uff20\u30de\u30f3\u30ac\u306e\u52a9\u3063\u4eba\u30de\u30b9\u30b1\u30c3\u30c8\uff5cnote\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/note.com\/lovebeer73\/n\/nc2ca89986260\" data-lkc-id=\"3000\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/8c98059cdf6332b6e4270119e99a21e53d68c7ac67f2f42da7184c20c71a1b49.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30de\u30f3\u30ac\u696d\u754cNews\u307e\u3068\u30811-210701\uff5c\u83ca\u6c60\u5065<\/div><div class=\"lkc-url\" title=\"https:\/\/note.com\/lovebeer73\/n\/nc2ca89986260\">https:\/\/note.com\/lovebeer73\/n\/nc2ca89986260<\/div><div class=\"lkc-excerpt\">\u30de\u30f3\u30ac\u696d\u754c\u95a2\u9023\u306e\u65e5\u3005\u306e\u30cb\u30e5\u30fc\u30b9\u3092\u307e\u3068\u3081\u308b\u30da\u30fc\u30b8\u3067\u3059\u3002  \u3057\u3070\u3089\u304f\u30c4\u30a4\u30c3\u30bf\u30fc\u3067\u5e73\u65e5\u6b63\u5348\u306b\u30a2\u30c3\u30d7\u3057\u3066\u3044\u305f\u3082\u306e\u3092\u3001\u8a66\u3057\u306bnote\u3067\u307e\u3068\u3081\u3066\u307f\u307e\u3059\u3002\u30ad\u30ea\u306e\u826f\u3044\u6240\u3067\u3001\u307e\u305f\u4ed6\u306e\u65b9\u6cd5\u3092\u8a66\u3057\u3066\u307f\u308b\u304b\u3082\u3057\u308c\u307e\u305b\u3093\u3002  ----  \u25a0Youtube\u30a2\u30cb\u30e1\u304c\u30d2\u30c3\u30c8\u3001\u5927\u624b\u3082\u53c2\u5165\uff08\u30de\u30f3\u30ac\u52d5\u753b\uff09     \u5c0f\u5b66\u9928\u3001\u96c6\u82f1\u793e\u3082\u53c2\u5165\u3000\u300cYouTube\u30a2\u30cb\u30e1\u300d\u304c\u30d2\u30c3\u30c8\u306e\u6e90\u6cc9\u306b\u30c6\u30ec\u30d3\u30a2\u30cb\u30e1\u3088\u308a\u7c21\u5358\u306b\u4f5c\u308c\u3066\u3001YouTube\u6f2b\u753b\u3088\u308a\u8868\u73fe\u304c\u8c4a\u304b\u3002\u4e21\u8005\u306e\u9577\u6240\u3092\u4f75\u305b\u6301\u3064YouTube\u30a2\u30cb\u30e1...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=note.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">note.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u300c\u5e73\u585a\u5e02\u96fb\u5b50\u56f3\u66f8\u9928\u300d\u30b5\u30fc\u30d3\u30b9\u958b\u59cb \uff17\u6708\uff17\u65e5\uff08\u6c34\uff09\u5348\u524d\uff19\u6642\u304b\u3089 | \u5e73\u585a\u3008\u30bf\u30a6\u30f3\u30cb\u30e5\u30fc\u30b9\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.townnews.co.jp\/0605\/2021\/07\/01\/581158.html\" data-lkc-id=\"3001\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/73993144d8f0f758a418d571e2bcb49eae98d9025dace80a493d0362bb639bbf.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u96fb\u5b50\u56f3\u66f8\u9928\u30b5\u30fc\u30d3\u30b9\u958b\u59cb | \u5e73\u585a | \u30bf\u30a6\u30f3\u30cb\u30e5\u30fc\u30b9<\/div><div class=\"lkc-url\" title=\"https:\/\/www.townnews.co.jp\/0605\/2021\/07\/01\/581158.html\">https:\/\/www.townnews.co.jp\/0605\/2021\/07\/01\/581158.html<\/div><div class=\"lkc-excerpt\">\u30d1\u30bd\u30b3\u30f3\u3084\u30b9\u30de\u30db\u3092\u4f7f\u3063\u3066\u30a6\u30a7\u30d6\u30d6\u30e9\u30a6\u30b6\u4e0a\u3067\u96fb\u5b50\u66f8\u7c4d\u3092\u8aad\u3080\u3053\u3068\u304c\u3067\u304d\u308b\u300c\u5e73\u585a\u5e02\u96fb\u5b50\u56f3\u66f8\u9928\u300d\u304c\uff17\u6708\uff17\u65e5\uff08\u6c34\uff09\u5348\u524d\uff19\u6642\u304b\u3089\u30b5\u30fc\u30d3\u30b9\u3092\u958b\u59cb\u3059\u308b\u3002 \t \t\u3000\u8535\u66f8\u6570\u306f\u5b9f\u7528\u66f8\u3001\u5150...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.townnews.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.townnews.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u30c7\u30b8\u30bf\u30eb\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u306e\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u5185\u30fb\u56f3\u66f8\u9928\u9001\u4fe1\u9650\u5b9a\u516c\u958b\u30c7\u30b8\u30bf\u30eb\u5316\u8cc7\u6599\u306e\u753b\u50cf\u30c7\u30fc\u30bf\u3092\u8a66\u884c\u63d0\u4f9b\u3008\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9\u30fb\u30dd\u30fc\u30bf\u30eb\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/current.ndl.go.jp\/node\/44329\" data-lkc-id=\"2335\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c905d630317a84236caa04e2823d854382fc866d615248c6d6202e2e40a6de38.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u30c7\u30b8\u30bf\u30eb\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u306e\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u5185\u30fb\u56f3\u66f8\u9928\u9001\u4fe1\u9650\u5b9a\u516c\u958b\u30c7\u30b8\u30bf\u30eb\u5316\u8cc7\u6599\u306e\u753b\u50cf\u30c7\u30fc\u30bf\u3092\u8a66\u884c\u63d0\u4f9b<\/div><div class=\"lkc-url\" title=\"https:\/\/current.ndl.go.jp\/node\/44329\">https:\/\/current.ndl.go.jp\/node\/44329<\/div><div class=\"lkc-excerpt\">2021\u5e747\u6708\u304b\u3089\u3001\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\uff08NDL\uff09\u306f\u3001\u300c\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u30c7\u30b8\u30bf\u30eb\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u300d\u306e\u3046\u3061\u3001\u8ee2\u8f09\u7b49\u3092\u76ee\u7684\u3068\u3057\u305f\u5229\u7528\u306b\u9650\u308a\u3001\u516c\u958b\u7bc4\u56f2\u304c\u300c\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\uff0f\u56f3\u66f8\u9928\u9001\u4fe1\u53c2\u52a0\u9928\u5185\u516c\u958b\u300d\u307e\u305f\u306f\u300c\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u5185\u516c\u958b\u300d\u3068\u306a\u3063\u3066\u3044\u308b\u753b\u50cf\u30c7\u30fc\u30bf\u306e\u8a66\u884c\u63d0\u4f9b\u3092<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=current.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">current.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u65e5\u672c\u306bSpotify\u306e\u30b9\u30bf\u30b8\u30aa\u958b\u8a2d\u3001\u30dd\u30c3\u30c9\u30ad\u30e3\u30b9\u30c8\u5f37\u5316\u306e\u72d9\u3044\u3068\u306f\u3008Engadget \u65e5\u672c\u7248\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/japanese.engadget.com\/spotify-210354792.html\" data-lkc-id=\"3002\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fjapanese.engadget.com%2Fspotify-210354792.html?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">Engadget | Technology News &amp; Reviews<\/div><div class=\"lkc-url\" title=\"https:\/\/japanese.engadget.com\/spotify-210354792.html\">https:\/\/japanese.engadget.com\/spotify-210354792.html<\/div><div class=\"lkc-excerpt\">Find the latest technology news and expert tech product reviews. Learn about the latest gadgets and consumer tech products for entertainment, gaming, lifestyle and more.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=japanese.engadget.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">japanese.engadget.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">60\u5104\u5186\u306e\u640d\u5bb3\u3092\u51fa\u3057\u305f\u300cDMM\u30d6\u30c3\u30af\u30b9\u300d70\uff05OFF\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\u65e9\u671f\u7d42\u4e86\u306e\u88cf\u5074\u3092\u8cac\u4efb\u8005\u3068\u4f1a\u9577\u306b\u805e\u3044\u305f\u3002\u3008DMM inside\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/inside.dmm.com\/entry\/2021\/07\/01\/dmm-books\" data-lkc-id=\"3003\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/14d0be285ad3022cfca4d2903bb9396e20d5dfe965932ac1b06bde227bdfaf4d.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">60\u5104\u5186\u306e\u640d\u5bb3\u3092\u51fa\u3057\u305f\u300cDMM\u30d6\u30c3\u30af\u30b9\u300d70\uff05OFF\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\u65e9\u671f\u7d42\u4e86\u306e\u88cf\u5074 - DMM inside<\/div><div class=\"lkc-url\" title=\"https:\/\/inside.dmm.com\/entry\/2021\/07\/01\/dmm-books\">https:\/\/inside.dmm.com\/entry\/2021\/07\/01\/dmm-books<\/div><div class=\"lkc-excerpt\">\uff5cDMM inside<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=inside.dmm.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">inside.dmm.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u96fb\u5b50\u66f8\u7c4d\u304b\u3089\u3082\u30aa\u30fc\u30c7\u30a3\u30aa\u30d6\u30c3\u30af\u304b\u3089\u3082\u306f\u307f\u51fa\u3059\u3082\u306e\u306e\u305f\u3081\u306b\u3008JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jepa.or.jp\/keyperson_message\/202107_5311\/\" data-lkc-id=\"2345\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f6814e87ba16cc6e5b0212d5eb2ab3e57958ff9fb85f5adfc42c24dd064e4331.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a  \u96fb\u5b50\u66f8\u7c4d\u304b\u3089\u3082\u30aa\u30fc\u30c7\u30a3\u30aa\u30d6\u30c3\u30af\u304b\u3089\u3082\u306f\u307f\u51fa\u3059\u3082\u306e\u306e\u305f\u3081\u306b<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jepa.or.jp\/keyperson_message\/202107_5311\/\">https:\/\/www.jepa.or.jp\/keyperson_message\/202107_5311\/<\/div><div class=\"lkc-excerpt\">\u30001987\u5e74\u306b\u300e\u5e83\u8f9e\u82d1\u3000\u7b2c\u4e09\u7248CD-ROM\u7248\u300f\u3092\u767a\u58f2\u3057\u3066\u4ee5\u6765\u3001\u5ca9\u6ce2\u66f8\u5e97\u306f\u7a2e\u3005\u69d8\u3005\u306a\u5185\u5bb9\u306e\u96fb\u5b50\u51fa\u7248\u3092\u8a66\u307f\u3066\u304d\u307e\u3057\u305f\u3002\u4eca\u56de\u306f\u305b\u3063\u304b\u304f\u306e\u6a5f\u4f1a\u3092\u9802\u6234\u3057\u307e\u3057\u305f\u306e\u3067\u3001\u3044\u307e\u3001\u79c1\u305f\u3061\u304c\u914d\u4fe1\u4e2d\u306e\uff08\u305d\u3057\u3066\u914d\u4fe1\u6e96\u5099\u4e2d\u306e\uff09\u3084\u3084\u73cd\u3057\u3044\u5f62\u614b\u306e\u96fb\u5b50\u66f8\u7c4d\u3092\u3054\u7d39\u4ecb\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u3001\u3042\u308f\u305b\u3066\u73fe\u5728\u76f4\u9762\u3057\u3066\u3044\u308b\u554f\u984c\u3082\u5171\u6709\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u305f\u3044\u3068...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jepa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jepa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">KADOKAWA\u30d3\u30b8\u30cd\u30b9\u30d7\u30ed\u30c7\u30e5\u30fc\u30b9\u5c40 \u4e8b\u696d\u79fb\u7ba1\u306e\u304a\u77e5\u3089\u305b\u3008\u682a\u5f0f\u4f1a\u793eKADOKAWA\u306e\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008784.000007006.html\" data-lkc-id=\"3004\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c62341f4aed8ba37009b2139053508f37d5f48a6c366da83d1073cc4bb54169b.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">KADOKAWA\u30d3\u30b8\u30cd\u30b9\u30d7\u30ed\u30c7\u30e5\u30fc\u30b9\u5c40 \u4e8b\u696d\u79fb\u7ba1\u306e\u304a\u77e5\u3089\u305b<\/div><div class=\"lkc-url\" title=\"https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008784.000007006.html\">https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008784.000007006.html<\/div><div class=\"lkc-excerpt\">\u682a\u5f0f\u4f1a\u793eKADOKAWA\u306e\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff082021\u5e747\u67081\u65e5 17\u664200\u5206\uff09KADOKAWA\u30d3\u30b8\u30cd\u30b9\u30d7\u30ed\u30c7\u30e5\u30fc\u30b9\u5c40 \u4e8b\u696d\u79fb\u7ba1\u306e\u304a\u77e5\u3089\u305b<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=prtimes.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">prtimes.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u89d2\u5ddd\u6b66\u8535\u91ce\u30df\u30e5\u30fc\u30b8\u30a2\u30e0\u300c\u30de\u30f3\u30ac\u30fb\u30e9\u30ce\u30d9\u56f3\u66f8\u9928\u300d\u304c7\u67088\u65e5\uff08\u6728\uff09\u306b\u30ea\u30cb\u30e5\u30fc\u30a2\u30eb\u30aa\u30fc\u30d7\u30f3\uff01\u30e9\u30ce\u30d9\u306b\u7279\u5316\u3057\u305f\u300c\u30c0\u30fb\u30f4\u30a3\u30f3\u30c1\u30b9\u30c8\u30a2\u300d\u30b5\u30c6\u30e9\u30a4\u30c8\u5e97\u3082\u65b0\u8a2d | \u5546\u54c1\u30fb\u30b5\u30fc\u30d3\u30b9\u30c8\u30d4\u30c3\u30af\u30b9\u3008KADOKAWA\u30b0\u30eb\u30fc\u30d7 \u30dd\u30fc\u30bf\u30eb\u30b5\u30a4\u30c8\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/group.kadokawa.co.jp\/information\/promotional_topics\/article-2970.html\" data-lkc-id=\"3005\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/5694a6500fac0b16716fb54d7d157c5bb815404f7fe66bb8118b1986fdff226b.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u89d2\u5ddd\u6b66\u8535\u91ce\u30df\u30e5\u30fc\u30b8\u30a2\u30e0\u300c\u30de\u30f3\u30ac\u30fb\u30e9\u30ce\u30d9\u56f3\u66f8\u9928\u300d\u304c7\u67088\u65e5\uff08\u6728\uff09\u306b\u30ea\u30cb\u30e5\u30fc\u30a2\u30eb\u30aa\u30fc\u30d7\u30f3\uff01\u30e9\u30ce\u30d9\u306b\u7279\u5316\u3057\u305f\u300c\u30c0\u30fb\u30f4\u30a3\u30f3\u30c1\u30b9\u30c8\u30a2\u300d\u30b5\u30c6\u30e9\u30a4\u30c8\u5e97\u3082\u65b0\u8a2d |  \u5546\u54c1\u30fb\u30b5\u30fc\u30d3...<\/div><div class=\"lkc-url\" title=\"https:\/\/group.kadokawa.co.jp\/information\/promotional_topics\/article-2970.html\">https:\/\/group.kadokawa.co.jp\/information\/promotional_topics\/article-2970.html<\/div><div class=\"lkc-excerpt\">\u3000\u682a\u5f0f\u4f1a\u793eKADOKAWA\uff08\u672c\u793e\uff1a\u6771\u4eac\u90fd\u5343\u4ee3\u7530\u533a\u3001\u4ee3\u8868\u53d6\u7de0\u5f79\u793e\u9577\uff1a\u590f\u91ce\u525b \u4ee5\u4e0b KADOKAWA\uff09\u3068\u3001\u516c\u76ca\u8ca1\u56e3\u6cd5\u4eba \u89d2\u5ddd\u6587\u5316\u632f\u8208\u8ca1\u56e3\uff08\u6240\u5728\u5730\uff1a\u6771\u4eac\u90fd\u5343\u4ee3\u7530\u533a\u3001\u7406\u4e8b\u9577\uff1a\u89d2\u5ddd\u6b74\u5f66\u3001\u4ee5\u4e0b \u89d2\u5ddd\u6587\u5316\u632f\u8208\u8ca1\u56e3\uff09\u306f\u3001\u57fc\u7389\u770c\u6240\u6ca2\u5e02\u300c\u3068\u3053\u308d\u3056\u308f\u30b5\u30af\u30e9\u30bf\u30a6\u30f3...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=group.kadokawa.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">group.kadokawa.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u96fb\u901a\u3001\u30a4\u30e9\u30b9\u30c8\u30fb\u6f2b\u753b\u7279\u5316\u578b\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3\u300cTwillust\u300d\u306e\u63d0\u4f9b\u958b\u59cb\u3008\u96fb\u901a\u306e\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9 | \u5171\u540c\u901a\u4fe1PR\u30ef\u30a4\u30e4\u30fc\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/kyodonewsprwire.jp\/release\/202106307062\" data-lkc-id=\"3006\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/10b1d729cd4ca5e6bdfcab5f770277f6ef338dd24752c8db9a36c648c9fc9a69.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u96fb\u901a\u3001\u30a4\u30e9\u30b9\u30c8\u30fb\u6f2b\u753b\u7279\u5316\u578b\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3\u300cTwillust\u300d\u306e\u63d0\u4f9b\u958b\u59cb<\/div><div class=\"lkc-url\" title=\"https:\/\/kyodonewsprwire.jp\/release\/202106307062\">https:\/\/kyodonewsprwire.jp\/release\/202106307062<\/div><div class=\"lkc-excerpt\">\u3000\u682a\u5f0f\u4f1a\u793e\u96fb\u901a\uff08\u672c\u793e\uff1a\u6771\u4eac\u90fd\u6e2f\u533a\u3001\u793e\u9577\uff1a\u4e94\u5341\u5d50 \u535a\u3001\u4ee5\u4e0b\u300c\u96fb\u901a\u300d\uff09\u306f\u3001\u56fd\u5185\u96fb\u901a\u30b0\u30eb\u30fc\u30d7\u6a2a\u65ad\u7d44\u7e54\u300cDentsu Japanimation Studio\u300d\uff08\u96fb\u901a\u30b8\u30e3\u30d1\u30cb\u30e1\u30fc\u30b7\u30e7\u30f3\u30b9\u30bf\u30b8\u30aa\u3001\u4ee5\u4e0b\u300cDJS\u300d...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=kyodonewsprwire.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">kyodonewsprwire.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u5c0f\u5b66\u9928\u300e\u65e5\u672c\u77ed\u7de8\u6f2b\u753b\u5091\u4f5c\u96c6\u300f\u3092\u300c\u5c11\u5e74\u9752\u5e74\u6f2b\u753b\u7de8\u300d\u306e\u30b5\u30d6\u30bf\u30a4\u8ffd\u52a0\u3057\u767a\u58f2 \u300c\u5c11\u5973\u6f2b\u753b\u304c\u53ce\u9332\u3055\u308c\u3066\u3044\u306a\u3044\u300d\u3068\u306e\u6307\u6458\u3092\u53d7\u3051\u3008\u306d\u3068\u3089\u307c\uff082021\u5e746\u670830\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/nlab.itmedia.co.jp\/nl\/articles\/2106\/30\/news164.html\" data-lkc-id=\"2341\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/59d4a5244fca2b882e94c466c64bd7b349cc084a5f28760bbef2ef7b8522a04d.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u5c0f\u5b66\u9928\u300e\u65e5\u672c\u77ed\u7de8\u6f2b\u753b\u5091\u4f5c\u96c6\u300f\u3092\u300c\u5c11\u5e74\u9752\u5e74\u6f2b\u753b\u7de8\u300d\u306e\u30b5\u30d6\u30bf\u30a4\u8ffd\u52a0\u3057\u767a\u58f2\u3000\u5c0f\u5b66\u9928\u300c\u3054\u6307\u6458\u3092\u8e0f\u307e\u3048\u3066\u3001\u793e\u5185\u3067\u691c\u8a0e\u3057\u305f\u7d50\u679c\u300d<\/div><div class=\"lkc-url\" title=\"https:\/\/nlab.itmedia.co.jp\/nl\/articles\/2106\/30\/news164.html\">https:\/\/nlab.itmedia.co.jp\/nl\/articles\/2106\/30\/news164.html<\/div><div class=\"lkc-excerpt\">\u5c0f\u5b66\u9928\u306f6\u670830\u65e5\u3001\u304b\u306d\u3066\u767a\u8868\u3057\u3066\u3044\u305f\u56fd\u5185\u77ed\u7de8\u6f2b\u753b\u30a2\u30f3\u30bd\u30ed\u30b8\u30fc\u3092\u300e\u65e5\u672c\u77ed\u7de8\u6f2b\u753b\u5091\u4f5c\u96c6 \u5c11\u5e74\u9752\u5e74\u6f2b\u753b\u7de8\u300f\u306b\u6539\u984c\u3057\u3066\u767a\u58f2\u3057\u307e\u3057\u305f\u3002\u3082\u3068\u306f\u300e\u65e5\u672c\u77ed\u7de8\u6f2b\u753b\u5091\u4f5c\u96c6\u300f\u3068\u3044\u3046\u66f8\u540d\u3067\u767a\u8868\u3055\u308c\u3066\u3044\u307e\u3057\u305f\u304c\u3001\u53ce\u9332\u4f5c\u54c1\u306b\u5bfe\u3057\u300c\u9078\u8005\u306b\u5973\u6027\u304c\u3044\u306a\u3044\u300d\u300c\u5c11\u5973\u6f2b\u753b\u304c\u53ce\u9332\u3055\u308c\u3066\u3044\u306a\u3044\u300d\u3068\u3044\u3063\u305f\u6307\u6458\u304c\u76f8\u6b21\u3044\u3067\u3044\u2026<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=nlab.itmedia.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">nlab.itmedia.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u300c\u6587\u85dd\u300d\u304c\u5b9f\u58f2300\uff05\u306eV\u5b57\u56de\u5fa9 \u6587\u82b8\u8a8c\u306b\u5b66\u3076\u30d6\u30e9\u30f3\u30c7\u30a3\u30f3\u30b0\u8853\u3008\u65e5\u7d4c\u30af\u30ed\u30b9\u30c8\u30ec\u30f3\u30c9\uff082021\u5e746\u670830\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/xtrend.nikkei.com\/atcl\/contents\/casestudy\/00012\/00648\/\" data-lkc-id=\"3007\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/1aaaa3561cb14f232250028153bbb4c5ac83a2be8f1d9a8a7dd10f8402cfd6fa.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u300c\u6587\u85dd\u300d\u304c\u5b9f\u58f2300\uff05\u306eV\u5b57\u56de\u5fa9\u3000\u6587\u82b8\u8a8c\u306b\u5b66\u3076\u30d6\u30e9\u30f3\u30c7\u30a3\u30f3\u30b0\u8853<\/div><div class=\"lkc-url\" title=\"https:\/\/xtrend.nikkei.com\/atcl\/contents\/casestudy\/00012\/00648\/\">https:\/\/xtrend.nikkei.com\/atcl\/contents\/casestudy\/00012\/00648\/<\/div><div class=\"lkc-excerpt\">\u6cb3\u51fa\u66f8\u623f\u65b0\u793e\uff08\u6771\u4eac\u30fb\u6e0b\u8c37\uff09\u304c\u51fa\u7248\u3059\u308b\u5b63\u520a\u6587\u82b8\u8a8c\u300c\u6587\u85dd\u300d\u304c\u7570\u4f8b\u306e\u30d2\u30c3\u30c8\u3092\u7d9a\u3051\u3066\u3044\u308b\u30022019\u5e74\u6625\u306b\u30ea\u30cb\u30e5\u30fc\u30a2\u30eb\u3092\u5b9f\u65bd\u3057\u3001\u5b9f\u58f2\u90e8\u6570\u3092\u305d\u308c\u4ee5\u524d\u304b\u30893\u500d\u4ee5\u4e0a\u3082\u4f38\u3070\u3057\u305f\u3002\u65b0\u3057\u3044\u8aad\u8005\u5c64\u3092\u7372\u5f97\u3057\u3001\u9577\u5e74\u505c\u6ede\u3057\u3066\u3044\u305f\u6587\u82b8\u8a8c\u3092\u518d\u751f\u3055\u305b\u305f\u6226\u7565\u3068\u306f\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=xtrend.nikkei.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">xtrend.nikkei.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h3 class=\"selector3\">\u4e16\u754c<\/h3>\n<h4 class=\"selector4\">\u30a2\u30de\u30be\u30f3\u304c90\u5104\u5186\u3067\u4eba\u6c17\u30dd\u30c3\u30c9\u30ad\u30e3\u30b9\u30c8\u300cSmartLess\u300d\u3092\u72ec\u5360\u914d\u4fe1\u3078\u3008Forbes JAPAN\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/forbesjapan.com\/articles\/detail\/42133\" data-lkc-id=\"3008\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fforbesjapan.com%2Farticles%2Fdetail%2F42133?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30a2\u30de\u30be\u30f3\u304c90\u5104\u5186\u3067\u4eba\u6c17\u30dd\u30c3\u30c9\u30ad\u30e3\u30b9\u30c8\u300cSmartLess\u300d\u3092\u72ec\u5360\u914d\u4fe1\u3078 | Forbes JAPAN \u516c\u5f0f\u30b5\u30a4\u30c8\uff08\u30d5\u30a9\u30fc\u30d6\u30b9 \u30b8\u30e3\u30d1\u30f3\uff09<\/div><div class=\"lkc-url\" title=\"https:\/\/forbesjapan.com\/articles\/detail\/42133\">https:\/\/forbesjapan.com\/articles\/detail\/42133<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=forbesjapan.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">forbesjapan.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u8c6a\u5f53\u5c40\u3001\uff26\uff22\u30fb\u30b0\u30fc\u30b0\u30eb\u3068\u65b0\u805e\u696d\u754c\u306e\u56e3\u4f53\u4ea4\u6e09\u63d0\u6848 \u8a18\u4e8b\u4f7f\u7528\u5de1\u308a\u3008\u30ed\u30a4\u30bf\u30fc\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/nordot.app\/783206751309922304?c=491375730748638305\" data-lkc-id=\"3009\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fnordot.app%2F783206751309922304%3Fc%3D491375730748638305?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30a8\u30e9\u30fc<\/div><div class=\"lkc-url\" title=\"https:\/\/nordot.app\/783206751309922304?c=491375730748638305\">https:\/\/nordot.app\/783206751309922304?c=491375730748638305<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=nordot.app\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">nordot.app<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">Amazon\u3001\u300c\u30ab\u30fc\u30f3\u59d4\u54e1\u9577\u5916\u3057\u300d\u3092\u5606\u9858 FTC\u72ec\u7981\u8abf\u67fb\u3067\u3008\u65e5\u672c\u7d4c\u6e08\u65b0\u805e\uff082021\u5e747\u67081\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.nikkei.com\/article\/DGXZQOGN30EXT0Q1A630C2000000\/\" data-lkc-id=\"3010\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.nikkei.com%2Farticle%2FDGXZQOGN30EXT0Q1A630C2000000%2F?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">Amazon\u3001\u300c\u30ab\u30fc\u30f3\u59d4\u54e1\u9577\u5916\u3057\u300d\u3092\u5606\u9858\u3000FTC\u72ec\u7981\u8abf\u67fb\u3067 - \u65e5\u672c\u7d4c\u6e08\u65b0\u805e<\/div><div class=\"lkc-url\" title=\"https:\/\/www.nikkei.com\/article\/DGXZQOGN30EXT0Q1A630C2000000\/\">https:\/\/www.nikkei.com\/article\/DGXZQOGN30EXT0Q1A630C2000000\/<\/div><div class=\"lkc-excerpt\">\u3010\u30b7\u30ea\u30b3\u30f3\u30d0\u30ec\u30fc=\u767d\u77f3\u6b66\u5fd7\u3011\u7c73\u30a2\u30de\u30be\u30f3\u30fb\u30c9\u30c3\u30c8\u30fb\u30b3\u30e0\u304c\u7c73\u9023\u90a6\u53d6\u5f15\u59d4\u54e1\u4f1a\uff08FTC\uff09\u306b\u5bfe\u3057\u3001\u540c\u793e\u6279\u5224\u306e\u6025\u5148\u92d2\uff08\u305b\u3093\u307d\u3046\uff09\u3068\u3057\u3066\u77e5\u3089\u308c\u308b\u30ea\u30ca\u30fb\u30ab\u30fc\u30f3\u59d4\u54e1\u9577\u3092\u540c\u793e\u306b\u95a2\u9023\u3059\u308b\u53cd\u30c8\u30e9\u30b9\u30c8\u6cd5\uff08\u72ec\u5360\u7981\u6b62\u6cd5\uff09\u8abf\u67fb\u306a\u3069\u304b\u3089\u9664\u5916\u3059\u308b\u3088\u3046\u6c42\u3081\u308b\u5606\u9858\u66f8\u3092\u63d0\u51fa\u3057\u305f\u3053\u3068\u304c30\u65e5\u3001\u660e\u3089\u304b\u306b\u306a\u3063\u305f\u3002\u7c73\u5de8\u5927IT\uff08\u60c5\u5831\u6280\u8853\uff09\u3078\u306e\u898f\u5236\u5f37\u5316\u306b\u5411\u3051\u305f\u30d0\u30a4\u30c7\u30f3\u7c73\u653f\u6a29\u306e\u4eba\u4e8b\u306b\u3001\u300c\u7d50\u8ad6\u3042\u308a\u304d\u3060\u300d\u3068\u3057\u3066\u5f85\u3063\u305f\u3092\u304b\u3051\u305f\u3002\u30ab\u30fc\u30f3\u6c0f\u306f\u6cd5\u5b66\u8005\u3067\u3001\u30a2\u30de\u30be<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.nikkei.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.nikkei.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">2020 North American Comics Sales Grow to $1.28 Billion\u3008Publishers Weekly\uff082021\u5e746\u670830\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/86791-2020-north-american-comics-sales-grow-to-1-28-billion.html\" data-lkc-id=\"3011\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/61fc678ff7e18783b410b4cb5f4be1d05f699ba9f8a5269ddfa1c33d63635580.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">2020 North American Comics Sales Grow to $1.28 Billion<\/div><div class=\"lkc-url\" title=\"https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/86791-2020-north-american-comics-sales-grow-to-1-28-billion.html\">https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/86791-2020-north-american-comics-sales-grow-to-1-28-billion.html<\/div><div class=\"lkc-excerpt\">Combined sales of comics periodicals and graphic novels in North American in 2020 climbed to approximately $1.28 billion, according to a joint estimate by pop culture trade news sites ICv2 and Comichron.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.publishersweekly.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.publishersweekly.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h3 class=\"selector3\">\u30a4\u30d9\u30f3\u30c8<\/h3>\n<h4 class=\"selector4\">\u6751\u702c\u62d3\u7537\u5f01\u8b77\u58eb\u300c\u8457\u4f5c\u6a29\u5165\u9580\u30bb\u30df\u30ca\u30fc3\u300d \u3008JEPA\u30fbeBP\u5171\u50ac\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u67087\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jepa.or.jp\/seminar\/20210707\/\" data-lkc-id=\"2794\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f6814e87ba16cc6e5b0212d5eb2ab3e57958ff9fb85f5adfc42c24dd064e4331.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a  \u30da\u30fc\u30b8\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jepa.or.jp\/seminar\/20210707\/\">https:\/\/www.jepa.or.jp\/seminar\/20210707\/<\/div><div class=\"lkc-excerpt\">\u4e00\u822c\u793e\u56e3\u6cd5\u4eba \u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\u306e\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u96fb\u5b50\u51fa\u7248\u30fb\u7de8\u96c6\u3092\u8003\u3048\u308b\u51fa\u7248\u754c\u3068\u60c5\u5831\u7523\u696d\u754c\u5404\u793e\u306e\u56e3\u4f53\u3002\u30cb\u30e5\u30fc\u30b9\u3001\u8abf\u67fb\u5831\u544a\u3001\u96fb\u5b50\u51fa\u7248\u3068\u306f\u3001\u4f1a\u54e1\u9650\u5b9a\u60c5\u5831\u306a\u3069\u914d\u4fe1\u3057\u3066\u3044\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jepa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jepa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u5927\u897f\u5bff\u7537\uff08\u6821\u6b63\u8005\uff09\u00d7\u7267\u6751\u671d\u5b50\uff08\u6587\u7b46\u5bb6\uff09\u00d7\u4ef2\u4fe3\u6681\u751f\uff08\u7de8\u96c6\u8005\uff09\u300c\u65b0\u6642\u4ee3\u306e\u66f8\u304d\u624b\u304c\u5927\u5207\u306b\u3057\u305f\u3044\u6821\u6b63\u306e\u3053\u3053\u308d\u300d\u3008\u6e0b\u8c37LOFT9\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\u6709\uff09\uff0f7\u670812\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.loft-prj.co.jp\/schedule\/loft9\/183204\" data-lkc-id=\"2351\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f9bd47cd00e34b7af1a3768d285a4283e2a5ce468257e72176df969369c7da17.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u3010\u5ef6\u671f\u3011\u65b0\u6642\u4ee3\u306e\u66f8\u304d\u624b\u304c\u5927\u5207\u306b\u3057\u305f\u3044\u6821\u6b63\u306e\u3053\u3053\u308d<\/div><div class=\"lkc-url\" title=\"https:\/\/www.loft-prj.co.jp\/schedule\/loft9\/183204\">https:\/\/www.loft-prj.co.jp\/schedule\/loft9\/183204<\/div><div class=\"lkc-excerpt\">\u5f53\u30a4\u30d9\u30f3\u30c8\u306f\u3001\u7dca\u6025\u4e8b\u614b\u5ba3\u8a00\u3092\u53d7\u3051\u3066\u79cb\u4ee5\u964d\u306e\u5ef6\u671f\u304c\u6c7a\u5b9a\u81f4\u3057\u307e\u3057\u305f\u3002 \u203bPeatix\u3067\u3054\u4e88\u7d04\u9802\u3044\u305f\u7686\u69d8\u306f\u5168\u3066\u30ad\u30e3\u30f3\u30bb\u30eb\u3068\u3055\u305b\u3066\u9802\u304d\u307e\u3059\u3002 \u203b\u914d\u4fe1\u30c1\u30b1\u30c3\u30c8\u304a\u8cb7\u3044\u4e0a\u3052\u306e\u7686\u69d8\u306b\u306f\u500b\u5225\u306b\u3054\u9023\u7d61\u3055\u305b\u3066\u9802\u304d\u307e\u3059\u3002 \u307e<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.loft-prj.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.loft-prj.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30c7\u30b8\u30bf\u30eb\u6559\u79d1\u66f8\u306e\u666e\u53ca\u4fc3\u9032\u306b\u5411\u3051\u305f\u6280\u8853\u7684\u306a\u8ab2\u984c\u306b\u95a2\u3059\u308b\u30ef\u30fc\u30ad\u30f3\u30b0\u30b0\u30eb\u30fc\u30d7\uff08\u7b2c1\u56de\uff09\u3008\u6587\u90e8\u79d1\u5b66\u7701\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670815\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.mext.go.jp\/b_menu\/shingi\/chousa\/shotou\/157\/1422833_00027.html\" data-lkc-id=\"2796\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/5cfa54b5c879f60a051272ed313bd13b604671af3f24d723f3e2baa2cc55ae50.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30c7\u30b8\u30bf\u30eb\u6559\u79d1\u66f8\u306e\u666e\u53ca\u4fc3\u9032\u306b\u5411\u3051\u305f\u6280\u8853\u7684\u306a\u8ab2\u984c\u306b\u95a2\u3059\u308b\u30ef\u30fc\u30ad\u30f3\u30b0\u30b0\u30eb\u30fc\u30d7\uff08\u7b2c1\u56de\uff09\uff1a\u6587\u90e8\u79d1\u5b66\u7701<\/div><div class=\"lkc-url\" title=\"https:\/\/www.mext.go.jp\/b_menu\/shingi\/chousa\/shotou\/157\/1422833_00027.html\">https:\/\/www.mext.go.jp\/b_menu\/shingi\/chousa\/shotou\/157\/1422833_00027.html<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.mext.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.mext.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30bb\u30df\u30ca\u30fc\u300c\u6d77\u5916\u3067\u306e\u96fb\u5b50\u66f8\u7c4d\u6d41\u901a\u306e\u73fe\u72b6\u3068\u4eca\u5f8c\u306e\u53ef\u80fd\u6027\u300d\u3008\u96fb\u5b50\u51fa\u7248\u5236\u4f5c\u30fb\u6d41\u901a\u5354\u8b70\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670816\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/aebs.or.jp\/seminar20210716.html\" data-lkc-id=\"2797\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/0a22ae1a3363fb3d99638d3cdfc0ecac284f21e7401b72fb5a712f52b0f03549.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30bb\u30df\u30ca\u30fc\u3000\u6d77\u5916\u3067\u306e\u96fb\u5b50\u66f8\u7c4d\u6d41\u901a\u306e\u73fe\u72b6\u3068\u4eca\u5f8c\u306e\u53ef\u80fd\u6027<\/div><div class=\"lkc-url\" title=\"https:\/\/aebs.or.jp\/seminar20210716.html\">https:\/\/aebs.or.jp\/seminar20210716.html<\/div><div class=\"lkc-excerpt\">\u65e5\u672c\u304c\u8a87\u308b\u30b3\u30f3\u30c6\u30f3\u30c4\u3067\u3042\u308b\u51fa\u7248\u306e\u6d77\u5916\u5c55\u958b\u306b\u304a\u3044\u3066\u3001\u96fb\u5b50\u51fa\u7248\u306f\u5927\u304d\u306a\u53ef\u80fd\u6027\u3092\u79d8\u3081\u3066\u3044\u307e\u3059\u3002\u305d\u3053\u3067\u96fb\u5b50\u51fa\u7248\u306b\u3088\u308b\u6d77\u5916\u6d41\u901a\u306e\u73fe\u72b6\u3068\u4eca\u5f8c\u306e\u53ef\u80fd\u6027\u306b\u3064\u3044\u3066\u8b58\u8005\u306b\u5ea7\u8ac7\u4f1a\u5f62\u5f0f\u3067\u8a9e\u3063\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=aebs.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">aebs.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u9577\u5c3e\u771f\u5148\u751f\u3092\u3057\u306e\u3076\u4f1a\u306e\u3054\u6848\u5185\u3008\u4eac\u90fd\u5927\u5b66\u5de5\u5b66\u90e8 \u96fb\u6c17\u96fb\u5b50\u5de5\u5b66\u79d1\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670818\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.s-ee.t.kyoto-u.ac.jp\/ja\/news\/topics\/mmnagao\" data-lkc-id=\"2206\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f126c73d7e4f0efb2948352de2e7af1a379b7eab7d64e4187fe2b22d0c3e3c34.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u9577\u5c3e\u771f\u5148\u751f\u3092\u3057\u306e\u3076\u4f1a(\u30aa\u30f3\u30e9\u30a4\u30f3)\u306e\u3054\u6848\u5185<\/div><div class=\"lkc-url\" title=\"https:\/\/www.s-ee.t.kyoto-u.ac.jp\/ja\/news\/topics\/mmnagao\">https:\/\/www.s-ee.t.kyoto-u.ac.jp\/ja\/news\/topics\/mmnagao<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.s-ee.t.kyoto-u.ac.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.s-ee.t.kyoto-u.ac.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30b8\u30e3\u30d1\u30f3\u30b5\u30fc\u30c1(JapanSearch) \u6982\u8981\u7d39\u4ecb\u3008JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670820\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jepa.or.jp\/seminar\/20210720\/\" data-lkc-id=\"2207\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f6814e87ba16cc6e5b0212d5eb2ab3e57958ff9fb85f5adfc42c24dd064e4331.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a  \u30da\u30fc\u30b8\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jepa.or.jp\/seminar\/20210720\/\">https:\/\/www.jepa.or.jp\/seminar\/20210720\/<\/div><div class=\"lkc-excerpt\">\u4e00\u822c\u793e\u56e3\u6cd5\u4eba \u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\u306e\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u96fb\u5b50\u51fa\u7248\u30fb\u7de8\u96c6\u3092\u8003\u3048\u308b\u51fa\u7248\u754c\u3068\u60c5\u5831\u7523\u696d\u754c\u5404\u793e\u306e\u56e3\u4f53\u3002\u30cb\u30e5\u30fc\u30b9\u3001\u8abf\u67fb\u5831\u544a\u3001\u96fb\u5b50\u51fa\u7248\u3068\u306f\u3001\u4f1a\u54e1\u9650\u5b9a\u60c5\u5831\u306a\u3069\u914d\u4fe1\u3057\u3066\u3044\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jepa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jepa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u4e2d\u56fd\u51fa\u7248\u696d\u754c\u6700\u65b0\u4e8b\u60c5\u2015\u2015\u30d3\u30b8\u30cd\u30b9\u30e2\u30c7\u30eb\u30fb\u30b3\u30f3\u30c6\u30f3\u30c4\u30fb\u30b7\u30b9\u30c6\u30e0\u3008JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670827\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jepa.or.jp\/seminar\/20210727\/\" data-lkc-id=\"2209\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f6814e87ba16cc6e5b0212d5eb2ab3e57958ff9fb85f5adfc42c24dd064e4331.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a  \u30da\u30fc\u30b8\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jepa.or.jp\/seminar\/20210727\/\">https:\/\/www.jepa.or.jp\/seminar\/20210727\/<\/div><div class=\"lkc-excerpt\">\u4e00\u822c\u793e\u56e3\u6cd5\u4eba \u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\u306e\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u96fb\u5b50\u51fa\u7248\u30fb\u7de8\u96c6\u3092\u8003\u3048\u308b\u51fa\u7248\u754c\u3068\u60c5\u5831\u7523\u696d\u754c\u5404\u793e\u306e\u56e3\u4f53\u3002\u30cb\u30e5\u30fc\u30b9\u3001\u8abf\u67fb\u5831\u544a\u3001\u96fb\u5b50\u51fa\u7248\u3068\u306f\u3001\u4f1a\u54e1\u9650\u5b9a\u60c5\u5831\u306a\u3069\u914d\u4fe1\u3057\u3066\u3044\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jepa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jepa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30c7\u30b8\u30bf\u30eb\u793e\u4f1a\u306b\u5fc5\u8981\u306a\u60c5\u5831 \u30a2\u30af\u30bb\u30b7\u30d3\u30ea\u30c6\u30a3\u3008JDC\/JEPA\u5171\u50ac\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670830\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/kokucheese.com\/event\/index\/613430\/\" data-lkc-id=\"2212\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/b4a44f71edcee42afcaf33c98d911b1a104f46054b95d74e52c459be1d6761fb.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u3053\u304f\u3061\u30fc\u305a\u30d7\u30ed - \u7121\u6599\u3067\u4f7f\u3048\u308b\u30a4\u30d9\u30f3\u30c8\u30fb\u30bb\u30df\u30ca\u30fc\u306e\u544a\u77e5\u30fb\u96c6\u5ba2\u30b5\u30fc\u30d3\u30b9<\/div><div class=\"lkc-url\" title=\"https:\/\/kokucheese.com\/event\/index\/613430\/\">https:\/\/kokucheese.com\/event\/index\/613430\/<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=kokucheese.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">kokucheese.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u7b2c185\u56de\u6708\u4f8b\u4f1a\u300c\u30c7\u30b8\u30bf\u30eb\u30a2\u30fc\u30ab\u30a4\u30d6\u306e\u73fe\u5728\u300d\u3008\u4e09\u7530\u56f3\u66f8\u9928\u30fb\u60c5\u5831\u5b66\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f7\u670831\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"http:\/\/www.mslis.jp\/monthly.html\" data-lkc-id=\"822\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/http%3A%2F%2Fwww.mslis.jp%2Fmonthly.html?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">http:\/\/www.mslis.jp\/monthly.html<\/div><div class=\"lkc-url\" title=\"http:\/\/www.mslis.jp\/monthly.html\">http:\/\/www.mslis.jp\/monthly.html<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.mslis.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.mslis.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30af\u30e9\u30d6 \u30e9\u30a4\u30d6\u30e9\u30ea\u30fc \u2015 \u5c0f\u3055\u306a\u672c\u306e\u5c55\u89a7\u4f1a 8 \u2015 \u3008\u65e5\u672c\u51fa\u7248\u30af\u30e9\u30d6\uff0f5\u670814\u65e5\uff5e8\u670831\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/shuppan-club.jp\/archives\/event\/642\" data-lkc-id=\"2120\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fshuppan-club.jp%2Farchives%2Fevent%2F642?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30af\u30e9\u30d6 \u30e9\u30a4\u30d6\u30e9\u30ea\u30fc  \u2015 \u5c0f\u3055\u306a\u672c\u306e\u5c55\u89a7\u4f1a 8 \u2015\u30002021\u5e745\u670814\u65e5\uff08\u91d1\uff09\uff5e2021\u5e749\u670817\u65e5\uff08\u91d1\uff09\uff1c\u4f1a\u671f\u5ef6\u9577\u3068\u306a\u308a\u307e\u3057\u305f\uff1e | \u65e5\u672c\u51fa\u7248\u30af\u30e9\u30d6<\/div><div class=\"lkc-url\" title=\"https:\/\/shuppan-club.jp\/archives\/event\/642\">https:\/\/shuppan-club.jp\/archives\/event\/642<\/div><div class=\"lkc-excerpt\">\u00a0<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=shuppan-club.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">shuppan-club.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<div class=\"belowbox wp300 hcenter\">\n<div style=\"text-align: center\"><span class=\"brackets\"><strong>HON.jp\u3092\u30d5\u30a9\u30ed\u30fc\u3057\u3066\u6700\u65b0\u60c5\u5831\u3092\u30c1\u30a7\u30c3\u30af\uff01<\/strong><\/span><br \/>\n<a href=\"https:\/\/twitter.com\/HONjpNewsBlog?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-size=\"large\" data-show-screen-name=\"false\" data-dnt=\"true\" data-show-count=\"false\">Follow @HONjpNewsBlog<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div>\n<p><span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:24866,&quot;href&quot;:&quot;https:\\\/\\\/www.watch.impress.co.jp\\\/docs\\\/topic\\\/1333132.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251117185701\\\/https:\\\/\\\/www.watch.impress.co.jp\\\/docs\\\/topic\\\/1333132.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:38:31&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:23:55&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-31 13:23:55&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24839,&quot;href&quot;:&quot;https:\\\/\\\/synodos.jp\\\/culture\\\/24375&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210703094843\\\/https:\\\/\\\/synodos.jp\\\/culture\\\/24375&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:36:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 01:08:41&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-18 16:03:22&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-24 07:41:28&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-18 15:07:52&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:23:51&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-27 10:41:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 00:40:00&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-06-15 00:40:00&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24867,&quot;href&quot;:&quot;https:\\\/\\\/nordot.app\\\/783196643919626240?c=491375730748638305&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210701093327\\\/https:\\\/\\\/nordot.app\\\/783196643919626240?c=491375730748638305&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:38:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:24:00&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-31 13:24:00&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24837,&quot;href&quot;:&quot;https:\\\/\\\/business.nikkei.com\\\/atcl\\\/gen\\\/19\\\/00324\\\/062800001&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20230327110852\\\/https:\\\/\\\/business.nikkei.com\\\/atcl\\\/gen\\\/19\\\/00324\\\/062800001\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:36:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-26 11:20:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-06 18:40:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:24:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-11 03:38:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 00:40:09&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-06-15 00:40:09&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24868,&quot;href&quot;:&quot;https:\\\/\\\/dime.jp\\\/genre\\\/1155650&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20240915002655\\\/https:\\\/\\\/dime.jp\\\/genre\\\/1155650\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:38:38&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:31:27&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-31 13:31:27&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24869,&quot;href&quot;:&quot;https:\\\/\\\/note.com\\\/lovebeer73\\\/n\\\/nc2ca89986260&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24870,&quot;href&quot;:&quot;https:\\\/\\\/www.townnews.co.jp\\\/0605\\\/2021\\\/07\\\/01\\\/581158.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20220626144829\\\/https:\\\/\\\/www.townnews.co.jp\\\/0605\\\/2021\\\/07\\\/01\\\/581158.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:38:57&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:38:57&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24832,&quot;href&quot;:&quot;https:\\\/\\\/current.ndl.go.jp\\\/node\\\/44329&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20220425191652\\\/https:\\\/\\\/current.ndl.go.jp\\\/node\\\/44329&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:35:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 01:08:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-18 16:03:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-26 11:23:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-06 18:40:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-18 15:07:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:31:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-11 03:38:20&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-08 02:09:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-24 17:06:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 00:40:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-09 08:43:57&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-09 08:43:57&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24871,&quot;href&quot;:&quot;https:\\\/\\\/japanese.engadget.com\\\/spotify-210354792.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20220220213319\\\/https:\\\/\\\/japanese.engadget.com\\\/spotify-210354792.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 13:31:34&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-31 13:31:34&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24872,&quot;href&quot;:&quot;https:\\\/\\\/inside.dmm.com\\\/entry\\\/2021\\\/07\\\/01\\\/dmm-books&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20221126234624\\\/https:\\\/\\\/inside.dmm.com\\\/entry\\\/2021\\\/07\\\/01\\\/dmm-books&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:06&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:06&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24841,&quot;href&quot;:&quot;https:\\\/\\\/www.jepa.or.jp\\\/keyperson_message\\\/202107_5311&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24873,&quot;href&quot;:&quot;https:\\\/\\\/prtimes.jp\\\/main\\\/html\\\/rd\\\/p\\\/000008784.000007006.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20241130152303\\\/https:\\\/\\\/prtimes.jp\\\/main\\\/html\\\/rd\\\/p\\\/000008784.000007006.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:09&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:09&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24874,&quot;href&quot;:&quot;https:\\\/\\\/group.kadokawa.co.jp\\\/information\\\/promotional_topics\\\/article-2970.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20220705000624\\\/https:\\\/\\\/group.kadokawa.co.jp\\\/information\\\/promotional_topics\\\/article-2970.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:11&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:11&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24875,&quot;href&quot;:&quot;https:\\\/\\\/kyodonewsprwire.jp\\\/release\\\/202106307062&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250907203956\\\/https:\\\/\\\/kyodonewsprwire.jp\\\/release\\\/202106307062&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:14&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:14&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24836,&quot;href&quot;:&quot;https:\\\/\\\/nlab.itmedia.co.jp\\\/nl\\\/articles\\\/2106\\\/30\\\/news164.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250418041009\\\/https:\\\/\\\/nlab.itmedia.co.jp\\\/nl\\\/articles\\\/2106\\\/30\\\/news164.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:35:51&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-12 01:08:33&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-24 07:41:30&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-24 07:41:30&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24876,&quot;href&quot;:&quot;https:\\\/\\\/xtrend.nikkei.com\\\/atcl\\\/contents\\\/casestudy\\\/00012\\\/00648&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20221128020255\\\/https:\\\/\\\/xtrend.nikkei.com\\\/atcl\\\/contents\\\/casestudy\\\/00012\\\/00648\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:23&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:23&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24877,&quot;href&quot;:&quot;https:\\\/\\\/forbesjapan.com\\\/articles\\\/detail\\\/42133&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251015190449\\\/https:\\\/\\\/forbesjapan.com\\\/articles\\\/detail\\\/42133&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:26&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:26&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24878,&quot;href&quot;:&quot;https:\\\/\\\/nordot.app\\\/783206751309922304?c=491375730748638305&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210701093310\\\/https:\\\/\\\/nordot.app\\\/783206751309922304?c=491375730748638305&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:28&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:28&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24879,&quot;href&quot;:&quot;https:\\\/\\\/www.nikkei.com\\\/article\\\/DGXZQOGN30EXT0Q1A630C2000000&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250722041618\\\/https:\\\/\\\/www.nikkei.com\\\/article\\\/DGXZQOGN30EXT0Q1A630C2000000\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:39:31&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-08 08:39:31&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24880,&quot;href&quot;:&quot;https:\\\/\\\/www.publishersweekly.com\\\/pw\\\/by-topic\\\/industry-news\\\/comics\\\/article\\\/86791-2020-north-american-comics-sales-grow-to-1-28-billion.html&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24818,&quot;href&quot;:&quot;https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210707&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210618012424\\\/https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210707\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:34:38&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-02 17:17:43&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-26 20:21:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-06 05:56:56&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-11 06:13:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-26 23:00:40&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 15:00:57&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-21 23:00:54&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-25 00:17:31&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-28 07:03:07&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-31 18:20:38&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-04 17:21:18&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-09 06:46:52&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-13 01:28:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-17 10:24:22&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-21 04:23:01&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-26 23:16:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-30 19:21:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-06 16:46:02&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-10 18:24:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-13 22:54:46&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-13 22:54:46&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24771,&quot;href&quot;:&quot;https:\\\/\\\/www.loft-prj.co.jp\\\/schedule\\\/loft9\\\/183204&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251209115645\\\/https:\\\/\\\/www.loft-prj.co.jp\\\/schedule\\\/loft9\\\/183204&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:25:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 01:08:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-15 22:26:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-24 07:41:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-02 03:01:34&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-05 18:04:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-10 05:39:31&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-17 03:25:10&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-27 11:24:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-04 16:21:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-12 15:01:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-24 00:43:01&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-27 10:41:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-31 18:20:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-04 05:50:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-09 06:46:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 15:16:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-19 09:16:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-29 13:23:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-02 18:51:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-08 20:31:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-14 08:24:16&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 08:24:16&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24739,&quot;href&quot;:&quot;https:\\\/\\\/www.mext.go.jp\\\/b_menu\\\/shingi\\\/chousa\\\/shotou\\\/157\\\/1422833_00027.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250720102745\\\/https:\\\/\\\/www.mext.go.jp\\\/b_menu\\\/shingi\\\/chousa\\\/shotou\\\/157\\\/1422833_00027.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:18:59&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-15 22:26:20&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-22 03:01:04&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-27 02:14:24&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-04 17:45:25&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-13 11:45:48&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-25 04:16:57&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-11 22:19:10&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-27 08:36:47&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-08 12:00:25&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 15:01:00&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-26 07:59:49&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-01 19:51:54&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-15 15:16:49&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-23 10:08:09&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-29 02:58:19&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-07-04 05:26:45&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-07-11 08:52:39&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-14 16:22:47&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:22:47&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24729,&quot;href&quot;:&quot;https:\\\/\\\/aebs.or.jp\\\/seminar20210716.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20240614205019\\\/https:\\\/\\\/aebs.or.jp\\\/seminar20210716.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:18:11&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-16 17:26:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-20 05:41:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-27 02:14:24&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 11:45:33&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-20 16:34:14&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-25 04:17:04&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-06 19:39:20&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-11 22:19:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-20 12:00:16&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-27 08:36:46&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-08 12:00:21&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-25 08:37:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-01 18:47:07&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-15 15:16:42&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-23 10:08:37&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-29 02:58:24&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-04 05:26:52&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-11 08:52:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-14 16:22:50&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:22:50&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24701,&quot;href&quot;:&quot;https:\\\/\\\/www.s-ee.t.kyoto-u.ac.jp\\\/ja\\\/news\\\/topics\\\/mmnagao&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20220703121743\\\/https:\\\/\\\/www.s-ee.t.kyoto-u.ac.jp\\\/ja\\\/news\\\/topics\\\/mmnagao&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:16:27&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-16 17:26:32&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-20 05:41:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-27 02:14:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 11:45:35&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-20 16:34:25&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-25 04:16:41&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-07 02:02:56&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-11 22:19:12&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-27 08:36:48&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-05 11:43:00&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 15:01:14&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-24 21:05:09&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-01 19:51:43&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-15 17:17:18&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-23 10:08:42&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-29 02:58:32&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-04 05:27:01&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-08 23:14:35&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-14 16:23:07&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:23:07&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24687,&quot;href&quot;:&quot;https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210720&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210624081242\\\/https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210720\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:15:30&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-27 02:14:23&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 11:45:33&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-25 04:16:55&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-07 02:02:48&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-11 22:19:07&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-27 08:36:42&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 15:01:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-24 21:04:57&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-01 19:52:02&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-15 13:09:57&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-23 10:08:45&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-29 02:58:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-04 05:27:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-08 23:14:46&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-14 16:22:53&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:22:53&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24645,&quot;href&quot;:&quot;https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210727&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210723161259\\\/https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210727\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:09:30&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-27 02:14:23&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-02 12:37:57&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-06 18:55:07&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 11:45:35&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-20 16:34:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-24 23:34:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-07 02:02:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-11 22:19:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-16 06:53:31&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-27 08:36:46&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-13 04:39:38&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-25 00:30:45&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-28 14:39:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-01 19:51:53&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-06 12:07:31&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-15 15:16:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-21 11:30:17&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-27 20:25:36&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-04 05:27:04&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-07 05:42:22&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-11 08:52:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-14 16:23:09&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:23:09&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24614,&quot;href&quot;:&quot;https:\\\/\\\/kokucheese.com\\\/event\\\/index\\\/613430&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210702033358\\\/https:\\\/\\\/kokucheese.com\\\/event\\\/index\\\/613430\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 08:02:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-13 05:32:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-16 17:26:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-20 05:41:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-27 02:14:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-02 12:38:03&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-06 18:55:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 11:45:53&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-25 04:17:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-07 02:02:52&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-11 22:19:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-16 06:53:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-27 08:36:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-13 04:39:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-25 00:51:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-29 06:17:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-04 10:20:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 13:10:07&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-21 11:30:26&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-27 20:25:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-04 05:27:11&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-07-07 05:42:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-11 08:52:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-14 16:22:58&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 16:22:58&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:16514,&quot;href&quot;:&quot;http:\\\/\\\/www.mslis.jp\\\/monthly.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20240527154714\\\/https:\\\/\\\/www.mslis.jp\\\/monthly.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-07 03:12:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-11 13:03:22&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-15 16:49:17&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-20 11:30:50&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-24 21:21:22&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-01 20:55:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-06 18:55:19&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-12 16:32:04&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-16 19:04:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-21 01:57:11&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-24 23:35:02&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-01 02:41:23&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-06 14:20:34&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-09 15:54:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-13 10:47:08&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-16 19:54:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-20 12:00:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-24 04:01:48&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-27 06:30:25&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-06 18:07:11&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-13 02:34:09&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-16 17:53:35&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-21 04:34:08&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-24 10:36:18&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-27 22:26:54&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-31 05:49:37&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-04 09:28:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-07 09:32:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-11 21:17:24&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-16 22:51:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-20 11:33:35&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-23 21:39:33&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-27 20:25:42&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-01 19:27:39&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-05 16:26:09&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-07-09 06:05:05&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-13 04:33:10&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-13 04:33:10&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:24385,&quot;href&quot;:&quot;https:\\\/\\\/shuppan-club.jp\\\/archives\\\/event\\\/642&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251118191735\\\/https:\\\/\\\/shuppan-club.jp\\\/archives\\\/event\\\/642&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 07:30:35&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-12 18:36:22&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-16 17:26:29&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-21 14:14:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-25 08:28:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-02 01:56:05&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-06 18:55:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-11 11:00:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-15 01:19:34&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-21 21:55:58&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-25 04:17:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-30 12:15:52&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-05 21:00:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 19:59:02&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-14 01:37:21&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-17 20:31:17&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-26 23:00:44&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-05 11:43:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-10 12:36:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-14 16:26:01&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-18 18:33:21&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-21 18:59:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-25 00:17:16&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-28 04:54:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-31 05:49:39&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-03 07:06:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-06 08:35:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-09 08:49:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-12 16:56:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 17:29:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-18 21:41:55&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-06-22 22:58:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-26 14:57:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-29 22:12:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-03 06:06:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-06 09:04:44&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-07-09 16:05:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-12 18:07:41&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-12 18:07:41&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:14854,&quot;href&quot;:&quot;https:\\\/\\\/twitter.com\\\/HONjpNewsBlog?ref_src=twsrc%5Etfw&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20230109190918\\\/https:\\\/\\\/twitter.com\\\/HONjpNewsBlog?ref_src=twsrc%5Etfw&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-06 23:31:26&quot;,&quot;http_code&quot;:400}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-06 23:31:26&quot;,&quot;http_code&quot;:400},&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>\u3000\u4f1d\u7d71\u7684\u306a\u53d6\u6b21\uff06\u66f8\u5e97\u6d41\u901a\u306e\u5546\u696d\u51fa\u7248\u304b\u3089\u3001\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u3092\u6d3b\u7528\u3057\u305f\u30c7\u30b8\u30bf\u30eb\u30d1\u30d6\u30ea\u30c3\u30b7\u30f3\u30b0\u307e\u3067\u3001\u5e83\u3044\u610f\u5473\u3067\u306e\u51fa\u7248\u306b\u95a2\u9023\u3059\u308b\u30cb\u30e5\u30fc\u30b9\u3092\u30c7\u30a4\u30ea\u30fc\u3067\u307e\u3068\u3081\u3066\u3044\u307e\u3059\u3002<\/p>\n<\/div>","protected":false},"author":9,"featured_media":30933,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAoiEM2xMfscec3m5-RpsRDKVy0:productID":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1992],"tags":[381,2069,306,91,112,1677,2044,214,718,85,99,1168,1170,69,102,224,2100,562,356,106,1036,152,136,2049,2099,54],"class_list":{"0":"post-31142","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-daily-news-summary","8":"tag-amazon","9":"tag-clubhouse","10":"tag-dmm","11":"tag-jepa","12":"tag-kadokawa","13":"tag-podcast","14":"tag-spotify","15":"tag-twitter","16":"tag-718","17":"tag-85","18":"tag-99","19":"tag-1168","20":"tag-1170","21":"tag-69","22":"tag-102","23":"tag-224","24":"tag-2100","25":"tag-562","26":"tag-356","27":"tag-106","28":"tag-1036","29":"tag-152","30":"tag-136","31":"tag-2049","32":"tag-2099","33":"tag-54"},"jetpack_featured_media_url":"https:\/\/hon.jp\/news\/wp-content\/uploads\/2021\/04\/news-headline.jpg","jetpack_shortlink":"https:\/\/wp.me\/p71Ph0-86i","jetpack_sharing_enabled":true,"brizy_media":[],"_links":{"self":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/31142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/comments?post=31142"}],"version-history":[{"count":1,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/31142\/revisions"}],"predecessor-version":[{"id":31143,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/31142\/revisions\/31143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/media\/30933"}],"wp:attachment":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/media?parent=31142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/categories?post=31142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/tags?post=31142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}