{"id":30794,"date":"2021-03-27T06:00:50","date_gmt":"2021-03-26T21:00:50","guid":{"rendered":"https:\/\/hon.jp\/news\/?p=30794"},"modified":"2021-10-18T16:51:58","modified_gmt":"2021-10-18T07:51:58","slug":"%e6%97%a5%e5%88%8a%e5%87%ba%e7%89%88%e3%83%8b%e3%83%a5%e3%83%bc%e3%82%b9%e3%81%be%e3%81%a8%e3%82%81-2021-03-27","status":"publish","type":"post","link":"https:\/\/hon.jp\/news\/1.0\/0\/30794","title":{"rendered":"\u65e5\u520a\u51fa\u7248\u30cb\u30e5\u30fc\u30b9\u307e\u3068\u3081 2021.03.27"},"content":{"rendered":"<p>\u3000\u4f1d\u7d71\u7684\u306a\u53d6\u6b21\uff06\u66f8\u5e97\u6d41\u901a\u306e\u5546\u696d\u51fa\u7248\u304b\u3089\u3001\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u3092\u6d3b\u7528\u3057\u305f\u30c7\u30b8\u30bf\u30eb\u30d1\u30d6\u30ea\u30c3\u30b7\u30f3\u30b0\u307e\u3067\u3001\u5e83\u3044\u610f\u5473\u3067\u306e\u51fa\u7248\u306b\u95a2\u9023\u3059\u308b\u30cb\u30e5\u30fc\u30b9\u3092\u30c7\u30a4\u30ea\u30fc\u3067\u307e\u3068\u3081\u3066\u3044\u307e\u3059\u3002<br \/>\n<!--more--><\/p>\n<h3 class=\"selector3\">\u56fd\u5185<\/h3>\n<h4 class=\"selector4\">DNP\u304c\u300c\u30d0\u30fc\u30c1\u30e3\u30eb\u66f8\u5e97\u300d\u3002\u81ea\u5b85\u3067\u672c\u3068\u306e\u5076\u767a\u7684\u306a\u51fa\u4f1a\u3044\u3008Impress Watch\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.watch.impress.co.jp\/docs\/news\/1314621.html\" data-lkc-id=\"3167\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/1d1b052add32bc071b46118f8f77aaf3bcd5be06e872a1f571175221ea4945f5.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30b8\u30e5\u30f3\u30af\u5802\u304c\u300c\u30d0\u30fc\u30c1\u30e3\u30eb\u66f8\u5e97\u300d\u306b\u3002\u81ea\u5b85\u3067\u672c\u3068\u306e\u5076\u767a\u7684\u306a\u51fa\u4f1a\u3044<\/div><div class=\"lkc-url\" title=\"https:\/\/www.watch.impress.co.jp\/docs\/news\/1314621.html\">https:\/\/www.watch.impress.co.jp\/docs\/news\/1314621.html<\/div><div class=\"lkc-excerpt\">\u5927\u65e5\u672c\u5370\u5237(DNP)\u306f\u30013\u670827\u65e5\u30aa\u30fc\u30d7\u30f3\u306e\u30c6\u30ec\u30d3\u6771\u4eac\u904b\u55b6\u300c\u6c60\u888b\u30df\u30e9\u30fc\u30ef\u30fc\u30eb\u30c9\u300d\u306b\u53c2\u753b\u3002DNP\u30b0\u30eb\u30fc\u30d7\u306e\u30b8\u30e5\u30f3\u30af\u5802\u66f8\u5e97\u6c60\u888b\u672c\u5e97\u3092\u300c\u30d0\u30fc\u30c1\u30e3\u30eb\u30b8\u30e5\u30f3\u30af\u5802\u66f8\u5e97\u6c60\u888b\u672c\u5e97\u300d\u3068\u3057\u3066\u6c60\u888b\u30df\u30e9\u30fc\u30ef\u30fc\u30eb\u30c9\u306b\u69cb\u7bc9\u3057\u3001\u300c\u30d0\u30fc\u30c1\u30e3\u30eb\u66f8\u5e97\u300d\u306e\u4e8b\u696d\u5316\u306b\u53d6\u308a\u7d44\u3080\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.watch.impress.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.watch.impress.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u5e2f\u5e83\u5e02\u56f3\u66f8\u9928\u304c\u300c\u96fb\u5b50\u56f3\u66f8\u9928\u300d\u958b\u8a2d \uff14\u6708\u304b\u3089\u30c7\u30b8\u30bf\u30eb\u5316\u5bfe\u5fdc\u306e\u65b0\u30b5\u30fc\u30d3\u30b9\u3008\u5341\u52dd\u6bce\u65e5\u65b0\u805e\u96fb\u5b50\u7248\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/kachimai.jp\/article\/index.php?no=529384\" data-lkc-id=\"3782\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/3fee6e930934487e0b6df0061df99a6cc8bbf27fce08c4d4a78a467170a8469e.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u5e2f\u5e83\u5e02\u56f3\u66f8\u9928\u304c\u300c\u96fb\u5b50\u56f3\u66f8\u9928\u300d\u958b\u8a2d\u3000\uff14\u6708\u304b\u3089\u30c7\u30b8\u30bf\u30eb\u5316\u5bfe\u5fdc\u306e\u65b0\u30b5\u30fc\u30d3\u30b9\uff08\u5341\u52dd\u6bce\u65e5\u65b0\u805e\uff09<\/div><div class=\"lkc-url\" title=\"https:\/\/kachimai.jp\/article\/index.php?no=529384\">https:\/\/kachimai.jp\/article\/index.php?no=529384<\/div><div class=\"lkc-excerpt\">\u3000\u5e2f\u5e83\u5e02\u56f3\u66f8\u9928\u306f\uff11\uff10\uff11\u5e74\u76ee\u3092\u8fce\u3048\u305f\u4eca\u5e74\u3001\u30c7\u30b8\u30bf\u30eb\u9762\u306e\u5f37\u5316\u3092\u56f3\u308b\u3002\uff14\u6708\uff11\u65e5\u304b\u3089\u306f\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u300c\u5e2f\u5e83\u5e02\u96fb\u5b50\u56f3\u66f8\u9928\u300d\u3092\u958b\u8a2d\u3002\u30b9\u30de\u30fc\u30c8\u30d5\u30a9\u30f3\uff08\u30b9\u30de\u30db\uff09\u306a\u3069\u306e\u7aef\u672b\u304c\u3042\u308c\u3070\u3001\u6765\u9928\u304c\u96e3\u3057\u3044\u5834\u5408\u3067\u3082\u4e00\u90e8\u56f3\u66f8\u3092\u96fb\u5b50...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=kachimai.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">kachimai.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306e\u5168\u30b3\u30df\u30c3\u30af\u30ec\u30fc\u30d9\u30eb\u304c\u53c2\u52a0\uff01\u300c\u30aa\u30fc\u30eb\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306b\u3088\u308b\u7e26\u30b9\u30af\u30ed\u30fc\u30eb\u6f2b\u753b\u5927\u8cde\u300d\u304c3\u670826\u65e5\uff08\u91d1\uff09\u304b\u3089\u52df\u96c6\u958b\u59cb\uff01\u3008\u682a\u5f0f\u4f1a\u793eKADOKAWA\u306e\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008361.000007006.html\" data-lkc-id=\"3783\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/81daa877f962157135a51142f985ce9174f12ba67aba0d35bc60752c42f18b89.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306e\u5168\u30b3\u30df\u30c3\u30af\u30ec\u30fc\u30d9\u30eb\u304c\u53c2\u52a0\uff01\u300c\u30aa\u30fc\u30eb\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306b\u3088\u308b\u7e26\u30b9\u30af\u30ed\u30fc\u30eb\u6f2b\u753b\u5927\u8cde\u300d\u304c3\u670826\u65e5\uff08\u91d1\uff09\u304b\u3089\u52df\u96c6\u958b\u59cb\uff01<\/div><div class=\"lkc-url\" title=\"https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008361.000007006.html\">https:\/\/prtimes.jp\/main\/html\/rd\/p\/000008361.000007006.html<\/div><div class=\"lkc-excerpt\">\u682a\u5f0f\u4f1a\u793eKADOKAWA\u306e\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff082021\u5e743\u670826\u65e5 13\u664254\u5206\uff09\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306e\u5168\u30b3\u30df\u30c3\u30af\u30ec\u30fc\u30d9\u30eb\u304c\u53c2\u52a0\uff01\u300c\u30aa\u30fc\u30eb\uff2b\uff21\uff24\uff2f\uff2b\uff21\uff37\uff21\u306b\u3088\u308b\u7e26\u30b9\u30af\u30ed\u30fc\u30eb\u6f2b\u753b\u5927\u8cde\u300d\u304c3\u670826\u65e5\uff08\u91d1\uff09\u304b\u3089\u52df\u96c6\u958b\u59cb\uff01<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=prtimes.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">prtimes.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u696d\u52d9\u63d0\u643a\u3001\u682a\u5f0f\u306e\u58f2\u51fa\u3057\u3001\u4e3b\u8981\u682a\u4e3b\u53ca\u3073\u4e3b\u8981\u682a\u4e3b\u3067\u3042\u308b\u7b46\u982d\u682a\u4e3b\u306e\u7570\u52d5\u4e26\u3073\u306b\u305d\u306e\u4ed6\u306e\u95a2\u4fc2\u4f1a\u793e\uff08\u89aa\u4f1a\u793e\u7b49\uff09\u306e\u7570\u52d5\u306e\u4e88\u5b9a\u306b\u95a2\u3059\u308b\u304a\u77e5\u3089\u305b\uff08PDF\uff09\u3008\u682a\u5f0f\u4f1a\u793e\u5bcc\u58eb\u5c71\u30de\u30ac\u30b8\u30f3\u30b5\u30fc\u30d3\u30b9\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/contents.xj-storage.jp\/xcontents\/AS08114\/70082a8d\/0e10\/469b\/861a\/5bfcd3ea342d\/140120210325484839.pdf\" data-lkc-id=\"3169\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fcontents.xj-storage.jp%2Fxcontents%2FAS08114%2F70082a8d%2F0e10%2F469b%2F861a%2F5bfcd3ea342d%2F140120210325484839.pdf?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">https:\/\/contents.xj-storage.jp\/xcontents\/AS08114\/70082a8d\/0e10\/469b\/861a\/5bfcd3ea342d\/140120210325484839.pdf<\/div><div class=\"lkc-url\" title=\"https:\/\/contents.xj-storage.jp\/xcontents\/AS08114\/70082a8d\/0e10\/469b\/861a\/5bfcd3ea342d\/140120210325484839.pdf\">https:\/\/contents.xj-storage.jp\/xcontents\/AS08114\/70082a8d\/0e10\/469b\/861a\/5bfcd3ea342d\/140120210325484839.pdf<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=contents.xj-storage.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">contents.xj-storage.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u682a\u5f0f\u58f2\u8cb7\u5951\u7d04\u53ca\u3073\u696d\u52d9\u63d0\u643a\u5951\u7d04\u7de0\u7d50\u306e\u304a\u77e5\u3089\u305b\uff08PDF\uff09\u3008\u682a\u5f0f\u4f1a\u793e\u56f3\u66f8\u9928\u6d41\u901a\u30bb\u30f3\u30bf\u30fc\uff08TRC\uff09\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.trc.co.jp\/information\/pdf\/20210326_TRCrelease.pdf\" data-lkc-id=\"3784\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.trc.co.jp%2Finformation%2Fpdf%2F20210326_TRCrelease.pdf?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">https:\/\/www.trc.co.jp\/information\/pdf\/20210326_TRCrelease.pdf<\/div><div class=\"lkc-url\" title=\"https:\/\/www.trc.co.jp\/information\/pdf\/20210326_TRCrelease.pdf\">https:\/\/www.trc.co.jp\/information\/pdf\/20210326_TRCrelease.pdf<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.trc.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.trc.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u7d0d\u672c\u5236\u5ea6\u5be9\u8b70\u4f1a\u304b\u3089\u7b54\u7533\u304c\u63d0\u51fa\u3055\u308c\u307e\u3057\u305f\uff08\u4ed8\u30fb\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff09\u3008\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u2015National Diet Library\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.ndl.go.jp\/jp\/news\/fy2020\/210326_01.html\" data-lkc-id=\"3158\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.ndl.go.jp%2Fjp%2Fnews%2Ffy2020%2F210326_01.html?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">\u7d0d\u672c\u5236\u5ea6\u5be9\u8b70\u4f1a\u304b\u3089\u7b54\u7533\u304c\u63d0\u51fa\u3055\u308c\u307e\u3057\u305f\uff08\u4ed8\u30fb\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\uff09\uff5c\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u2015National Diet Library<\/div><div class=\"lkc-url\" title=\"https:\/\/www.ndl.go.jp\/jp\/news\/fy2020\/210326_01.html\">https:\/\/www.ndl.go.jp\/jp\/news\/fy2020\/210326_01.html<\/div><div class=\"lkc-excerpt\">\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u304c\u767a\u4fe1\u3059\u308b\u65b0\u7740\u60c5\u5831\u306e\u4e00\u89a7\u3067\u3059\u3002\u30d7\u30ec\u30b9\u30ea\u30ea\u30fc\u30b9\u3001\u30cb\u30e5\u30fc\u30b9\u3001\u520a\u884c\u7269\u3001\u63a1\u7528\u60c5\u5831\u306e\u65b0\u7740\u60c5\u5831\u306e\u4e00\u89a7\u304c\u3042\u308a\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u7d42\u520a\u306b\u3042\u305f\u3063\u3066 | NDL\u66f8\u8a8c\u60c5\u5831\u30cb\u30e5\u30fc\u30b9\u30ec\u30bf\u30fc2021\u5e741\u53f7\u3008\u56fd\u7acb\u56fd\u4f1a\u56f3\u66f8\u9928\u2015National Diet Library\uff082021\u5e743\u670826\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.ndl.go.jp\/jp\/data\/bib_newsletter\/2021_1\/article_01.html\" data-lkc-id=\"3785\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.ndl.go.jp%2Fjp%2Fdata%2Fbib_newsletter%2F2021_1%2Farticle_01.html?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">https:\/\/www.ndl.go.jp\/jp\/data\/bib_newsletter\/2021_1\/article_01.html<\/div><div class=\"lkc-url\" title=\"https:\/\/www.ndl.go.jp\/jp\/data\/bib_newsletter\/2021_1\/article_01.html\">https:\/\/www.ndl.go.jp\/jp\/data\/bib_newsletter\/2021_1\/article_01.html<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u30e1\u30c7\u30a3\u30a2\u30c9\u30a5 \u65e5\u672c\u6587\u82b8\u793e\u3092\u5b50\u4f1a\u793e\u5316\u3001\u30a4\u30f3\u30d7\u30ea\u30f3\u30c8\u4e8b\u696d\u306b\u6ce8\u529b\u3008\u6587\u5316\u901a\u4fe1\u30c7\u30b8\u30bf\u30eb\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.bunkanews.jp\/article\/230820\/\" data-lkc-id=\"3164\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/68571f4cff626f98c233701422e9326c6f5f4532f323e50e52d103624069c7e8.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30e1\u30c7\u30a3\u30a2\u30c9\u30a5\u3000\u65e5\u672c\u6587\u82b8\u793e\u3092\u5b50\u4f1a\u793e\u5316\u3001\u30a4\u30f3\u30d7\u30ea\u30f3\u30c8\u4e8b\u696d\u306b\u6ce8\u529b - \u6587\u5316\u901a\u4fe1\u30c7\u30b8\u30bf\u30eb<\/div><div class=\"lkc-url\" title=\"https:\/\/www.bunkanews.jp\/article\/230820\/\">https:\/\/www.bunkanews.jp\/article\/230820\/<\/div><div class=\"lkc-excerpt\">\u00a0 \u3000\u96fb\u5b50\u66f8\u7c4d\u53d6\u6b21\u6700\u5927\u624b\u306e\u30e1\u30c7\u30a3\u30a2\u30c9\u30a5\u306f\uff13\u670825\u65e5\u3001\u65e5\u672c\u6587\u82b8\u793e\u306e\u767a\u884c\u6e08\u307f\u5168\u682a\u5f0f\u3092\uff32\uff29\uff3a\uff21\uff30\u30b0\u30eb\u30fc\u30d7\u304b\u3089\u53d6\u5f97\u3057\u3001\u540c30\u65e5\u4ed8\u3067\u5b8c\u5168\u5b50\u4f1a\u793e\u5316\u3059\u308b\u3068\u767a\u8868\u3057\u305f\u3002\u53d6\u5f97\u4fa1\u984d\u306f\u7d0415\u5104\u5186\u3002 \u00a0 \u3000\u2026\u7d9a\u304d<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.bunkanews.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.bunkanews.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u6a2a\u6d5c\u5e02\u7acb\u56f3\u66f8\u9928\u304c\u300c\u96fb\u5b50\u66f8\u7c4d\u300d\u30b5\u30fc\u30d3\u30b9\u3092\u958b\u59cb \u30b9\u30de\u30db\u3067\u672c\u304c\u501f\u308a\u3089\u308c\u308b\u3008\u30e8\u30b3\u30cf\u30de\u7d4c\u6e08\u65b0\u805e\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.hamakei.com\/headline\/11264\/\" data-lkc-id=\"3786\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/658f1ebe467124811043a89abf0842215299b6de1043d50954ff53cdfa1d804b.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u6a2a\u6d5c\u5e02\u7acb\u56f3\u66f8\u9928\u304c\u300c\u96fb\u5b50\u66f8\u7c4d\u300d\u30b5\u30fc\u30d3\u30b9\u3092\u958b\u59cb\u3000\u30b9\u30de\u30db\u3067\u672c\u304c\u501f\u308a\u3089\u308c\u308b<\/div><div class=\"lkc-url\" title=\"https:\/\/www.hamakei.com\/headline\/11264\/\">https:\/\/www.hamakei.com\/headline\/11264\/<\/div><div class=\"lkc-excerpt\">\u6a2a\u6d5c\u5e02\u7acb\u56f3\u66f8\u9928\u306f3\u670824\u65e5\u3001\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u306b\u3064\u306a\u3044\u3060\u30d1\u30bd\u30b3\u30f3\u3084\u30b9\u30de\u30fc\u30c8\u30d5\u30a9\u30f3\u3001\u30bf\u30d6\u30ec\u30c3\u30c8\u3092\u4f7f\u3063\u3066\u3001\u96fb\u5b50\u66f8\u7c4d\u306e\u8cb8\u51fa\u30fb\u8fd4\u5374\u304c\u3067\u304d\u308b\u300c\u6a2a\u6d5c\u5e02\u7acb\u56f3\u66f8\u9928\u96fb\u5b50\u66f8\u7c4d\u30b5\u30fc\u30d3\u30b9\u300d\u3092\u958b\u8a2d\u3057\u305f\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.hamakei.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.hamakei.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u8d64\u88f8\u3005\u306a\u6570\u5b57\u3082\u516c\u958b\uff01Media Innovation\u306e\u30b5\u30d6\u30b9\u30af1\u5e74\u9593\u3092\u632f\u308a\u8fd4\u308b\u30fb\u30fb\u30fb\u7279\u96c6\u300c\u9032\u5316\u3059\u308b\u30b5\u30d6\u30b9\u30af\u300d#2\u3008Media Innovation\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/media-innovation.jp\/2021\/03\/25\/mi-subscription-1year-review\/\" data-lkc-id=\"3787\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f5940cff32115f5f5e0acb7bed83ed59925ff792dc9dbad27228d1116f13aa52.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u8d64\u88f8\u3005\u306a\u6570\u5b57\u3082\u516c\u958b\uff01Media Innovation\u306e\u30b5\u30d6\u30b9\u30af1\u5e74\u9593\u3092\u632f\u308a\u8fd4\u308b\u30fb\u30fb\u30fb\u7279\u96c6\u300c\u9032\u5316\u3059\u308b\u30b5\u30d6\u30b9\u30af\u300d#2 | Media Innovation \/ \u30c7\u30b8\u30bf\u30eb\u30e1\u30c7\u30a3\u30a2\u306e\u30a4\u30ce\u30d9\u30fc\u30b7\u30e7\u30f3\u3092\u52a0\u901f\u3055\u305b\u308b<\/div><div class=\"lkc-url\" title=\"https:\/\/media-innovation.jp\/2021\/03\/25\/mi-subscription-1year-review\/\">https:\/\/media-innovation.jp\/2021\/03\/25\/mi-subscription-1year-review\/<\/div><div class=\"lkc-excerpt\">Media Innovation\u306e2021\u5e743\u6708\u7279\u96c6\u306f\u300c\u9032\u5316\u3059\u308b\u30b5\u30d6\u30b9\u30af\u300d\u3002\u4eca\u3084\u30e1\u30c7\u30a3\u30a2\u306b\u3068\u3063\u3066\u6700\u91cd\u8981\u306e\u30d3\u30b8\u30cd\u30b9\u30e2\u30c7\u30eb\u306b\u4f4d\u7f6e\u4ed8\u3051\u3089\u308c\u3064\u3064\u6709\u308b\u30b5\u30d6\u30b9\u30af\u30ea\u30d7\u30b7\u30e7\u30f3\u3002\u56fd\u5185\u3067\u3082\u30c8\u30e9\u30a4\u3059\u308b\u30d1\u30d6\u30ea\u30c3\u30b7\u30e3\u30fc\u304c\u5897\u52a0\u3057\u3001\u4eca\u307e\u3067\u306e\u3088\u3046\u306b\u30d3\u30b8\u30cd\u30b9\u30d1\u30fc\u30bd\u30f3\u306b\u8a34\u6c42\u3059\u308b\u4ee5\u5916\u306e\u30e1\u30c7\u30a3\u30a2\u3082\u5897\u3048\u3066\u304d\u307e\u3057\u2026<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=media-innovation.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">media-innovation.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u66f8\u5354\u3068VIPO\u3001\u300cJapan Book Bank\u300d\u3092\u958b\u8a2d\u3008\u65b0\u6587\u5316\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.shinbunka.co.jp\/news2021\/03\/210325-04.htm\" data-lkc-id=\"3166\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.shinbunka.co.jp%2Fnews2021%2F03%2F210325-04.htm?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30da\u30fc\u30b8\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3067\u3057\u305f \u2013 \u65b0\u6587\u5316\u30aa\u30f3\u30e9\u30a4\u30f3<\/div><div class=\"lkc-url\" title=\"https:\/\/www.shinbunka.co.jp\/news2021\/03\/210325-04.htm\">https:\/\/www.shinbunka.co.jp\/news2021\/03\/210325-04.htm<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.shinbunka.co.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.shinbunka.co.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">E2367 &#8211; \u65b0\u3057\u3044\u5b66\u8853\u60c5\u5831\u691c\u7d22\u57fa\u76e4\u300cCiNii Research\u300d\u30d7\u30ec\u7248\u306b\u3064\u3044\u3066\u3008\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9\u30fb\u30dd\u30fc\u30bf\u30eb\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/current.ndl.go.jp\/e2367\" data-lkc-id=\"3788\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c905d630317a84236caa04e2823d854382fc866d615248c6d6202e2e40a6de38.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">E2367 \u2013 \u65b0\u3057\u3044\u5b66\u8853\u60c5\u5831\u691c\u7d22\u57fa\u76e4\u300cCiNii Research\u300d\u30d7\u30ec\u7248\u306b\u3064\u3044\u3066<\/div><div class=\"lkc-url\" title=\"https:\/\/current.ndl.go.jp\/e2367\">https:\/\/current.ndl.go.jp\/e2367<\/div><div class=\"lkc-excerpt\">2020\u5e7411\u67086\u65e5\u306b\uff0c\u56fd\u7acb\u60c5\u5831\u5b66\u7814\u7a76\u6240\uff08NII\uff09\u306e\u30aa\u30fc\u30d7\u30f3\u30b5\u30a4\u30a8\u30f3\u30b9\u57fa\u76e4\u7814\u7a76\u30bb\u30f3\u30bf\u30fc\uff08RCOS\uff1bE1925\u53c2\u7167\uff09\u306f\uff0c\u65b0\u30b5\u30fc\u30d3\u30b9\u3067\u3042\u308b\u300cCiNii Research\u30d7\u30ec\u7248\u300d(\u4ee5\u4e0b\u300c\u30d7\u30ec\u7248\u300d)\u3092\u516c\u958b\u3057\u305f\u3002\u672c\u30b5\u30fc\u30d3\u30b9\u306f2021\u5e744\u6708\u516c\u958b\u4e88\u5b9a\u306e\u300cCiNii Research\u300d\uff08\u4ee5\u4e0b\u300c\u672c\u516c\u958b\u7248\u300d\uff09\u306e\u5148\u884c\u30d0\u30fc\u30b8\u30e7\u30f3\u3068\u3057\u3066\uff0c\u8a66\u9a13\u7684\u306b\u30ea\u30ea\u30fc\u30b9\u3055\u308c\u305f\u3082\u306e\u3067\u3042\u308b\u3002\u672c\u7a3f\u3067\u306f\u300cCiNii Research\u300d\u306e\u958b\u767a\u306e\u7d4c\u7def\u3068\u4eca\u5f8c\u306b\u3064\u3044\u3066\u7d39\u4ecb\u3059\u308b\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=current.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">current.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">E2366 &#8211; JPRO\u306e\u66f8\u8a8c\u30c7\u30fc\u30bf\u30dd\u30fc\u30bf\u30eb\u30b5\u30a4\u30c8\u300cBooksPRO\u300d\u3008\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9\u30fb\u30dd\u30fc\u30bf\u30eb\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/current.ndl.go.jp\/e2366\" data-lkc-id=\"3789\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c905d630317a84236caa04e2823d854382fc866d615248c6d6202e2e40a6de38.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">E2366 \u2013 JPRO\u306e\u66f8\u8a8c\u30c7\u30fc\u30bf\u30dd\u30fc\u30bf\u30eb\u30b5\u30a4\u30c8\u300cBooksPRO\u300d<\/div><div class=\"lkc-url\" title=\"https:\/\/current.ndl.go.jp\/e2366\">https:\/\/current.ndl.go.jp\/e2366<\/div><div class=\"lkc-excerpt\">2020\u5e7411\u670816\u65e5\uff0c\u4e00\u822c\u793e\u56e3\u6cd5\u4eba\u65e5\u672c\u51fa\u7248\u30a4\u30f3\u30d5\u30e9\u30bb\u30f3\u30bf\u30fc\uff08JPO\uff09\u306e\u904b\u55b6\u3059\u308b\u51fa\u7248\u60c5\u5831\u767b\u9332\u30bb\u30f3\u30bf\u30fc\uff08JPRO\uff09\u306f\uff0c\u66f8\u5e97\u306e\u4ed5\u5165\u62c5\u5f53\u5411\u3051\u306b\u63d0\u4f9b\u3057\u3066\u3044\u305f\u30dd\u30fc\u30bf\u30eb\u30b5\u30a4\u30c8\u300cBooksPRO\u300d\u3092\u56f3\u66f8\u9928\u3067\u3082\u95b2\u89a7\u53ef\u80fd\u3068\u3057\u305f\u3002\u672c\u7a3f\u3067\u306f\uff0c\u305d\u306e\u7d4c\u7def\u3068\u73fe\u72b6\u306b\u3064\u3044\u3066\u7d39\u4ecb\u3059\u308b\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=current.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">current.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">NFT\u3092\u4f7f\u3063\u3066\u3001\u30b5\u30a4\u30f3\u672c\u3092\u58f2\u3063\u3066\u307f\u305f\u3008\u3046\u3081\uff5cnote\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/note.com\/ume_nanminchamp\/n\/n90bc1bbc8809\" data-lkc-id=\"3790\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/0445abe6fb1dbd84fb10f79efc326d4d682c21f7f8f83c0b02a58d8f4854cca0.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">NFT\u3092\u4f7f\u3063\u3066\u3001\u30b5\u30a4\u30f3\u672c\u3092\u58f2\u3063\u3066\u307f\u305f\uff5c\u3046\u3081<\/div><div class=\"lkc-url\" title=\"https:\/\/note.com\/ume_nanminchamp\/n\/n90bc1bbc8809\">https:\/\/note.com\/ume_nanminchamp\/n\/n90bc1bbc8809<\/div><div class=\"lkc-excerpt\">&quot;NFT&quot;\u3068\u3044\u3046\u8a00\u8449\u3092\u521d\u3081\u3066\u8033\u306b\u3057\u305f\u306e\u306f2\u9031\u9593\u304f\u3089\u3044\u524d\u3002 \u30d6\u30ed\u30c3\u30af\u30c1\u30a7\u30fc\u30f3\u306e\u3046\u3093\u3061\u3083\u3089\u3067\u3001\u30c7\u30b8\u30bf\u30eb\u30c7\u30fc\u30bf\u3092\u30a2\u30fc\u30c8\u3068\u3057\u3066\u8ca9\u58f2\u3059\u308b\uff1f\u306e\uff1f\u304f\u3089\u3044\u306e\u7406\u89e3\u3067\u3057\u305f\u3002 \u4eca\u306e\u7406\u89e3\u306f\u3053\u3093\u306a\u3068\u3053\u308d\u3067\u3059\u3002  \u30fbNFT\u3092\u4f7f\u3046\u3068\u3001\u30c7\u30fc\u30bf\u3054\u3068\u306b\u56fa\u6709\u306e\u3082\u306e\u3068\u3057\u3066\u6271\u308f\u308c\u3001\u8907\u88fd\u306f\u3067\u304d\u305a\u3001\u3061\u3083\u3093\u3068\u300c\u6240\u6709\u300d\u3067\u304d\u308b \u30fb\u8cfc\u5165\u3059\u308b\u306b\u306f\u3001\u30a4\u30fc\u30b5\u30ea\u30a6\u30e0\u3068\u3044\u3046\u6697\u53f7\u901a\u8ca8\u304c\u5fc5\u8981 \u30fb\u8cfc\u5165\u3057\u305f\u30c7\u30fc\u30bf\u306f\u8ee2\u58f2\u3067\u304d\u3066\u3001\u305d\u306e\u305f\u3073\u306b\u4f5c\u8005\u306b\u306f\u5370\u7a0e\u304c\u5165\u308b  \u3068\u3044\u3046\u308f\u3051\u3067\u3001\u3044\u307e\u3082\u300c\u7406...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=note.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">note.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">CA1994 &#8211; \u52d5\u5411\u30ec\u30d3\u30e5\u30fc\uff1a\u7d75\u56f3\u30fb\u53e4\u5730\u56f3\u306e\u30a6\u30a7\u30d6\u516c\u958b\u3068\u5dee\u5225\u8868\u73fe\u3078\u306e\u5bfe\u5fdc\u306e\u73fe\u72b6 \/ \u5965\u91ce\u5409\u5b8f\u3008\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9\u30fb\u30dd\u30fc\u30bf\u30eb\uff082021\u5e743\u670820\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/current.ndl.go.jp\/ca1994\" data-lkc-id=\"3791\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c905d630317a84236caa04e2823d854382fc866d615248c6d6202e2e40a6de38.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">CA1994 \u2013 \u52d5\u5411\u30ec\u30d3\u30e5\u30fc\uff1a\u7d75\u56f3\u30fb\u53e4\u5730\u56f3\u306e\u30a6\u30a7\u30d6\u516c\u958b\u3068\u5dee\u5225\u8868\u73fe\u3078\u306e\u5bfe\u5fdc\u306e\u73fe\u72b6 \/ \u5965\u91ce\u5409\u5b8f<\/div><div class=\"lkc-url\" title=\"https:\/\/current.ndl.go.jp\/ca1994\">https:\/\/current.ndl.go.jp\/ca1994<\/div><div class=\"lkc-excerpt\">PDF\u30d5\u30a1\u30a4\u30eb\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9 No.347\u30002021\u5e7403\u670820\u65e5 CA1994 \u52d5\u5411\u30ec\u30d3\u30e5\u30fc \u7d75\u56f3\u30fb\u53e4\u5730\u56f3\u306e\u30a6\u30a7\u30d6\u516c\u958b\u3068\u5dee\u5225\u8868\u73fe\u3078\u306e\u5bfe\u5fdc\u306e\u73fe\u72b6 \u95a2\u897f\u9928\u6587\u732e\u63d0\u4f9b\u8ab2\uff0f\u65e5\u672c\u56f3\u66f8\u9928\u5354\u4f1a\u56f3\u66f8\u9928\u306e\u81ea\u7531\u59d4\u54e1\u4f1a\uff1a\u5965\u91ce\u5409\u5b8f\uff08\u304a\u304f\u306e\u3088\u3057\u3072\u308d\uff09 \u306f\u3058\u3081\u306b<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=current.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">current.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h3 class=\"selector3\">\u4e16\u754c<\/h3>\n<h4 class=\"selector4\">\u30d5\u30a7\u30a4\u30b9\u30d6\u30c3\u30af\u304cClubhouse\u30af\u30ed\u30fc\u30f3\u306e\u30e9\u30a4\u30d6\u97f3\u58f0SNS\u6a5f\u80fd\u3092\u958b\u767a\u4e2d\u3008TechCrunch Japan\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/jp.techcrunch.com\/2021\/03\/25\/2021-03-23-facebooks-clubhouse-rival-looks-a-lot-like-clubhouse-right-now\/\" data-lkc-id=\"3792\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/5302bc93238fb63a9771ef6d906259b8f600e328b0a107ceb6770207fa4c68c0.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">TechCrunch<\/div><div class=\"lkc-url\" title=\"https:\/\/jp.techcrunch.com\/2021\/03\/25\/2021-03-23-facebooks-clubhouse-rival-looks-a-lot-like-clubhouse-right-now\/\">https:\/\/jp.techcrunch.com\/2021\/03\/25\/2021-03-23-facebooks-clubhouse-rival-looks-a-lot-like-clubhouse-right-now\/<\/div><div class=\"lkc-excerpt\">TechCrunch | Reporting on the business of technology, startups, venture capital funding, and Silicon Valley<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=jp.techcrunch.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">jp.techcrunch.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">Penguin Random House Will Distribute Marvel Comics to Comics Stores\u3008Publishers Weekly\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/85890-prhps-will-distribute-marvel-comics-to-comics-stores.html\" data-lkc-id=\"3793\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/46c3482a054d0d36fb07d5c3502bdacd73f060e26d9a7a7390238373f335825c.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">Penguin Random House Will Distribute Marvel Comics to Comics Stores<\/div><div class=\"lkc-url\" title=\"https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/85890-prhps-will-distribute-marvel-comics-to-comics-stores.html\">https:\/\/www.publishersweekly.com\/pw\/by-topic\/industry-news\/comics\/article\/85890-prhps-will-distribute-marvel-comics-to-comics-stores.html<\/div><div class=\"lkc-excerpt\">Penguin Random House Publisher Services has reached an agreement with Marvel to distribute its periodical comics and graphic novels to the comics shop market, also known as the direct market.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.publishersweekly.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.publishersweekly.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">E2368 &#8211; \u300c\u6b21\u4e16\u4ee3\u306e\u30e1\u30bf\u30c7\u30fc\u30bf\u3078\u306e\u79fb\u884c\u300d\u306b\u95a2\u3059\u308b\u5831\u544a\u66f8\u3008\u30ab\u30ec\u30f3\u30c8\u30a2\u30a6\u30a7\u30a2\u30cd\u30b9\u30fb\u30dd\u30fc\u30bf\u30eb\uff082021\u5e743\u670825\u65e5\uff09\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/current.ndl.go.jp\/e2368\" data-lkc-id=\"3794\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/c905d630317a84236caa04e2823d854382fc866d615248c6d6202e2e40a6de38.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">E2368 \u2013 \u300c\u6b21\u4e16\u4ee3\u306e\u30e1\u30bf\u30c7\u30fc\u30bf\u3078\u306e\u79fb\u884c\u300d\u306b\u95a2\u3059\u308b\u5831\u544a\u66f8<\/div><div class=\"lkc-url\" title=\"https:\/\/current.ndl.go.jp\/e2368\">https:\/\/current.ndl.go.jp\/e2368<\/div><div class=\"lkc-excerpt\">2020\u5e749\u6708\uff0cOCLC Research\u306f\uff0c\u6b21\u4e16\u4ee3\u306e\u30e1\u30bf\u30c7\u30fc\u30bf\u3078\u306e\u79fb\u884c\u306b\u95a2\u3059\u308b\u5831\u544a\u66f8\uff0c\u201cTransitioning to the Next Generation of Metadata\u201d \u3092\u516c\u958b\u3057\u305f\u3002\u672c\u5831\u544a\u306f\uff0c\u30e1\u30bf\u30c7\u30fc\u30bf\u30fb\u30de\u30cd\u30b8\u30e1\u30f3\u30c8\u306b\u95a2\u3059\u308b\u610f\u898b\u4ea4\u63db\u7b49\u306e\u6d3b\u52d5\u3092\u884c\u3046\u201cOCLC Research Library Partners Metadata Managers Focus Group\u201d \u306b\u3088\u308b\uff0c2015\u5e74\u304b\u30892020\u5e74\u306b\u304b\u3051\u3066\u306e\u8b70\u8ad6\u3084\u6b21\u4e16\u4ee3\u306e\u30e1\u30bf\u30c7\u30fc\u30bf\u306b\u95a2\u308f\u308b\u4e88\u6e2c\u306e\u96c6\u5927\u6210\u3067\u3042\u308a\uff0c\u8fd1\u5e74\u306e\u30e1\u30bf\u30c7\u30fc\u30bf\u306e\u5c55\u958b\u306e\u6982\u89b3\u3068\uff0c\u6b21\u4e16\u4ee3\u306e\u30e1\u30bf\u30c7\u30fc\u30bf...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=current.ndl.go.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">current.ndl.go.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h3 class=\"selector3\">\u30a4\u30d9\u30f3\u30c8<\/h3>\n<h4 class=\"selector4\">\u3010\u7279\u756a\u3011\u30de\u30f3\u30ac\u7523\u696d\u306e\u73fe\u5728\u3068\u672a\u6765 \u2015\u2015 HON.jp\u30d6\u30ed\u30fc\u30c9\u30ad\u30e3\u30b9\u30c6\u30a3\u30f3\u30b0 \/ \u30b2\u30b9\u30c8\uff1a\u83ca\u6c60\u5065\uff08\u6f2b\u753b\u306e\u52a9\u3063\u4eba\u30de\u30b9\u30b1\u30c3\u30c8\u5408\u540c\u4f1a\u793e\u4ee3\u8868\uff09\u3008HON.jp\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f3\u670827\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/honjp-broadcasting-special202103.peatix.com\/view\" data-lkc-id=\"785\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/3c21618f857b659a0a698694ebc51b52c833eb2aff4acd9ac6893f49131ae097.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u3010\u7279\u756a\u3011\u30de\u30f3\u30ac\u7523\u696d\u306e\u73fe\u5728\u3068\u672a\u6765 \u2015\u2015 HON.jp\u30d6\u30ed\u30fc\u30c9\u30ad\u30e3\u30b9\u30c6\u30a3\u30f3\u30b0 \/ \u30b2\u30b9\u30c8\uff1a\u83ca\u6c60\u5065\uff08\u6f2b\u753b\u306e\u52a9\u3063\u4eba\u30de\u30b9\u30b1\u30c3\u30c8\u5408\u540c\u4f1a\u793e\u4ee3\u8868\uff09<\/div><div class=\"lkc-url\" title=\"https:\/\/honjp-broadcasting-special202103.peatix.com\/view\">https:\/\/honjp-broadcasting-special202103.peatix.com\/view<\/div><div class=\"lkc-excerpt\">3\u670827\u65e5\u306f1\u6642\u9593\u306e\u7279\u756a\uff01 2\u670826\u65e5\u30fb27\u65e5\u306b\u958b\u50ac\u3055\u308c\u305fIMART2021\u306e\u30d7\u30ed\u30c7\u30e5\u30fc\u30b5\u30fc\u83ca\u6c60\u5065\u3055\u3093\u3092\u30b2\u30b9\u30c8\u306b\u8fce\u3048\u300c\u30de\u30f3\u30ac\u7523\u696d\u306e\u73fe\u5728\u3068\u672a\u6765\u300d\u3068\u3044\u3046\u30c6\u30fc\u30de\u3067\u6700\u8fd1\u306e\u30c8\u30d4\u30c3\u30af\u30b9\u3092\u6398\u308a\u4e0b... powered by Peatix : More than a ticket.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=honjp-broadcasting-special202103.peatix.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">honjp-broadcasting-special202103.peatix.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u81ea\u4e3b\u691c\u95b2\u304c\u5fc5\u8981\u306a\u73fe\u4ee3\u4f5c\u5bb6\u306e\u4e0d\u81ea\u7531\u3055 \u2015\u2015 HON.jp\u30d6\u30ed\u30fc\u30c9\u30ad\u30e3\u30b9\u30c6\u30a3\u30f3\u30b0 #33 \/ \u30b2\u30b9\u30c8\uff1a\u5927\u6d1e\u6566\u53f2\uff08\u53f0\u6e7e\u5728\u4f4f\u4f5c\u5bb6\u30fb\u7ffb\u8a33\u5bb6\uff09\u3008HON.jp\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f3\u670829\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/honjp-broadcasting-33.peatix.com\/view\" data-lkc-id=\"786\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/1261cebcf903f93ca53c05364d03c98d0f4f29be2c6ebde3b29dd490573a7969.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u81ea\u4e3b\u691c\u95b2\u304c\u5fc5\u8981\u306a\u73fe\u4ee3\u4f5c\u5bb6\u306e\u4e0d\u81ea\u7531\u3055 \u2015\u2015 HON.jp\u30d6\u30ed\u30fc\u30c9\u30ad\u30e3\u30b9\u30c6\u30a3\u30f3\u30b0 #33 \/ \u30b2\u30b9\u30c8\uff1a\u5927\u6d1e\u6566\u53f2\uff08\u53f0\u6e7e\u5728\u4f4f\u4f5c\u5bb6\u30fb\u7ffb\u8a33\u5bb6\uff09<\/div><div class=\"lkc-url\" title=\"https:\/\/honjp-broadcasting-33.peatix.com\/view\">https:\/\/honjp-broadcasting-33.peatix.com\/view<\/div><div class=\"lkc-excerpt\">3\u670829\u65e5\u306e\u30b2\u30b9\u30c8\u306f\u5927\u6d1e\u6566\u53f2\u3055\u3093\uff08\u53f0\u6e7e\u5728\u4f4f\u4f5c\u5bb6\u30fb\u7ffb\u8a33\u5bb6\uff09\u3067\u3059\u3002\u30a6\u30a7\u30d3\u30ca\u30fc\u53c2\u52a0\u8005\u3092\u52df\u96c6\u3057\u307e\u3059\u3002Zoom\u30df\u30fc\u30c6\u30a3\u30f3\u30b0\u30a2\u30d7\u30ea\uff08Windows\u3001Mac\u3001Android\u3001iPhone\uff09\u3082\u3057\u304f... powered by Peatix : More than a ticket.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=honjp-broadcasting-33.peatix.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">honjp-broadcasting-33.peatix.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">2021\u5e74\u65b0\u5165\u793e\u54e1\u7814\u4fee\u4f1a\u3008\u4e00\u822c\u793e\u56e3\u6cd5\u4eba\u65e5\u672c\u66f8\u7c4d\u51fa\u7248\u5354\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f4\u670813\u65e5\uff5e21\u65e5\u3009\u203b\u7533\u8fbc\u7de0\u5207\u306f3\u670831\u65e5<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jbpa.or.jp\/pdf\/documents\/shinjin2021.pdf\" data-lkc-id=\"787\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fwww.jbpa.or.jp%2Fpdf%2Fdocuments%2Fshinjin2021.pdf?w=200\" width=\"160px\" height=\"\" alt=\"\" \/><\/figure><div class=\"lkc-title\">404 Not Found<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jbpa.or.jp\/pdf\/documents\/shinjin2021.pdf\">https:\/\/www.jbpa.or.jp\/pdf\/documents\/shinjin2021.pdf<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jbpa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jbpa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u53e4\u66f8\u5e97\u4e3b\u304c\u767a\u4fe1\u3059\u308bYouTube \u2015\u2015 HON.jp News Casting #34 \/ \u30b2\u30b9\u30c8\uff1a\u5409\u6210\u79c0\u592b\uff08\u672d\u5e4c\u306e\u53e4\u66f8\u5e97\u4e3b\uff09\u3008HON.jp\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f4\u67085\u65e5\u3009\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/honjp-newscasting-34.peatix.com\/view\" data-lkc-id=\"3795\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/0fa81f25807f1f3a2372b281893cf994e850a743cfa28bfeebe1e9d2b91d2843.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u53e4\u66f8\u5e97\u4e3b\u304c\u767a\u4fe1\u3059\u308bYouTube \u2015\u2015 HON.jp News Casting #34 \/ \u30b2\u30b9\u30c8\uff1a\u5409\u6210\u79c0\u592b\uff08\u672d\u5e4c\u306e\u53e4\u66f8\u5e97\u4e3b\uff09<\/div><div class=\"lkc-url\" title=\"https:\/\/honjp-newscasting-34.peatix.com\/view\">https:\/\/honjp-newscasting-34.peatix.com\/view<\/div><div class=\"lkc-excerpt\">4\u67085\u65e5\u306e\u30b2\u30b9\u30c8\u306f\u5409\u6210\u79c0\u592b\u3055\u3093\uff08\u672d\u5e4c\u306e\u53e4\u66f8\u5e97\u4e3b\uff09\u3067\u3059\u3002\u30a6\u30a7\u30d3\u30ca\u30fc\u53c2\u52a0\u8005\u3092\u52df\u96c6\u3057\u307e\u3059\u3002Zoom\u30df\u30fc\u30c6\u30a3\u30f3\u30b0\u30a2\u30d7\u30ea\uff08Windows\u3001Mac\u3001Android\u3001iPhone\uff09\u3082\u3057\u304f\u306f\u30a6\u30a7\u30d6... powered by Peatix : More than a ticket.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=honjp-newscasting-34.peatix.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">honjp-newscasting-34.peatix.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">\u5fb3\u529b\u57fa\u5f66\u300c\u30d3\u30b8\u30cd\u30b9\u306b\u5f79\u7acb\u3064note\u3084SNS\u306e\u3064\u3065\u3051\u65b9\u300d\u3008note\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f4\u67085\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/note.com\/events\/n\/n8a9f7bc17eb4\" data-lkc-id=\"788\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/8b7a38b996e9c9dce652a2d3a3f5d9ea964f6960669e7123e94bd88f8cefef1f.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u30104\/5(\u6708)19\u6642\u3011\u300c\u30d3\u30b8\u30cd\u30b9\u306b\u5f79\u7acb\u3064note\u3084SNS\u306e\u3064\u3065\u3051\u65b9\u300d \u3092\u958b\u50ac\u3057\u307e\u3059\uff5cnote\u30a4\u30d9\u30f3\u30c8\u60c5\u5831<\/div><div class=\"lkc-url\" title=\"https:\/\/note.com\/events\/n\/n8a9f7bc17eb4\">https:\/\/note.com\/events\/n\/n8a9f7bc17eb4<\/div><div class=\"lkc-excerpt\">\u203b\u3053\u306e\u30a4\u30d9\u30f3\u30c8\u306f\u7d42\u4e86\u3057\u307e\u3057\u305f\u3001\u5f53\u65e5\u306e\u5185\u5bb9\u306f\u4e0b\u8a18\u306e\u52d5\u753b\u3067\u3054\u89a7\u306b\u306a\u308c\u307e\u3059\u3002          4\u67085\u65e5(\u6708)19\u6642\u304b\u3089\u300c\u30d3\u30b8\u30cd\u30b9\u306b\u5f79\u7acb\u3064note\u3084SNS\u306e\u3064\u3065\u3051\u65b9\u300d\u3068\u3044\u3046\u30c6\u30fc\u30de\u306e\u30aa\u30f3\u30e9\u30a4\u30f3\u30a4\u30d9\u30f3\u30c8\u3092\u958b\u50ac\u3057\u307e\u3059\u3002 \u4f1a\u793e\u54e1\u306e\u65b9\u3084\u4f01\u696d\u306b\u304a\u3051\u308bnote\u306e\u6d3b\u7528\u3092\u691c\u8a0e\u3055\u308c\u3066\u3044\u308b\u65b9\u306f\u3001\u662f\u975e\u3054\u53c2\u52a0\u4e0b\u3055\u3044\u3002  \u958b\u50ac\u80cc\u666f  \u300c\u30d3\u30b8\u30cd\u30b9\u306b\u5f79\u306b\u7acb\u3064\u5f62\u3067\u3001note\u3084SNS\u306e\u30a2\u30ab\u30a6\u30f3\u30c8\u3092\u4f5c\u3063\u3066\u307f\u305f\u3044\u3051\u3069\u3001\u4f55\u3092\u66f8\u3051\u3070\u826f\u3044\u306e\u304b\u601d\u3044\u3064\u304b\u306a\u3044\u300d \u300c\u4ed5\u4e8b\u306b\u5f79\u7acb\u3066\u3088\u3046\u3068\u3001note\u3084...<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=note.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">note.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">UDB TALK Vol.1\u300c\u66f8\u5e97\u3068\u672c\u306e\u672a\u77e5\u306a\u308b\u76ca\u300d\u68ee\u5ca1\u7763\u884c\u00d7\u5ddd\u4e0a\u6d69\u53f8\u3008\u682a\u5f0f\u4f1a\u793e\u30b9\u30de\u30a4\u30eb\u30ba\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f4\u670813\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/udbtalk01-202104.peatix.com\" data-lkc-id=\"789\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/32f5c8c56a96ada253b810af278dc349c7349164c274ff9d5ad632db98cfa9be.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">\u300a4\/13(\u706b)20:00\u958b\u50ac\u300bUDB TALK Vol.1\u300c\u66f8\u5e97\u3068\u672c\u306e\u672a\u77e5\u306a\u308b\u76ca\u300d\u68ee\u5ca1\u7763\u884c\u00d7\u5ddd\u4e0a\u6d69\u53f8<\/div><div class=\"lkc-url\" title=\"https:\/\/udbtalk01-202104.peatix.com\">https:\/\/udbtalk01-202104.peatix.com<\/div><div class=\"lkc-excerpt\">\u30b9\u30de\u30a4\u30eb\u30ba\u751f\u6d3b\u4fa1\u5024\u62e1\u5145\u7814\u7a76\u6240\u304c\u6bce\u6708\u4e3b\u50ac\u3059\u308b\u3001\u672a\u77e5\u306a\u308b\u76ca\u306e\u63a2\u7a76\u3068\u793e\u4f1a\u5b9f\u88c5\u306e\u305f\u3081\u306e\u30aa\u30fc\u30d7\u30f3\u30bb\u30c3\u30b7\u30e7\u30f3\uff01\u8a18\u5ff5\u3059\u3079\u304d\u3001\u7b2c\u4e00\u5f3e\u306e\u30c6\u30fc\u30de\u306f\u300c\u66f8\u5e97\u3068\u672c\u306e\u672a\u77e5\u306a\u308b\u76ca\u300d\u3002UDB TALK SESSI... powered by Peatix : More than a ticket.<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=udbtalk01-202104.peatix.com\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">udbtalk01-202104.peatix.com<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<h4 class=\"selector4\">SlowNews\u304c\u3064\u304f\u308b\u300c\u30ce\u30f3\u30d5\u30a3\u30af\u30b7\u30e7\u30f3\u306e\u672a\u6765\u300d\u702c\u5c3e\u5091\u3008JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\uff08\u30aa\u30f3\u30e9\u30a4\u30f3\uff09\uff0f4\u670814\u65e5\u3009<\/h4>\n<div class=\"linkcard\"><div class=\"lkc-external-wrap\"><a class=\"lkc-link no_icon\" href=\"https:\/\/www.jepa.or.jp\/seminar\/20210314\/\" data-lkc-id=\"790\" target=\"_blank\" rel=\"external noopener\"><div class=\"lkc-card\"><div class=\"lkc-content\"><figure class=\"lkc-thumbnail\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lkc-thumbnail-img\" src=\"https:\/\/i0.wp.com\/hon.jp\/news\/wp-content\/uploads\/pz-linkcard\/cache\/f6814e87ba16cc6e5b0212d5eb2ab3e57958ff9fb85f5adfc42c24dd064e4331.jpeg\"   alt=\"\" \/><\/figure><div class=\"lkc-title\">JEPA\uff5c\u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a  \u30da\u30fc\u30b8\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/div><div class=\"lkc-url\" title=\"https:\/\/www.jepa.or.jp\/seminar\/20210314\/\">https:\/\/www.jepa.or.jp\/seminar\/20210314\/<\/div><div class=\"lkc-excerpt\">\u4e00\u822c\u793e\u56e3\u6cd5\u4eba \u65e5\u672c\u96fb\u5b50\u51fa\u7248\u5354\u4f1a\u306e\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u3059\u3002\u96fb\u5b50\u51fa\u7248\u30fb\u7de8\u96c6\u3092\u8003\u3048\u308b\u51fa\u7248\u754c\u3068\u60c5\u5831\u7523\u696d\u754c\u5404\u793e\u306e\u56e3\u4f53\u3002\u30cb\u30e5\u30fc\u30b9\u3001\u8abf\u67fb\u5831\u544a\u3001\u96fb\u5b50\u51fa\u7248\u3068\u306f\u3001\u4f1a\u54e1\u9650\u5b9a\u60c5\u5831\u306a\u3069\u914d\u4fe1\u3057\u3066\u3044\u307e\u3059\u3002<\/div><\/div><div class=\"lkc-info\"><div class=\"lkc-favicon\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.google.com\/s2\/favicons?domain=www.jepa.or.jp\" alt=\"\" width=\"16\" height=\"16\" \/><\/div><div class=\"lkc-domain\">www.jepa.or.jp<\/div><\/div><div class=\"clear\"><\/div><\/div><\/a><\/div><\/div>\n<div class=\"belowbox wp300 hcenter\">\n<div style=\"text-align: center\"><span class=\"brackets\"><strong>HON.jp\u3092\u30d5\u30a9\u30ed\u30fc\u3057\u3066\u6700\u65b0\u60c5\u5831\u3092\u30c1\u30a7\u30c3\u30af\uff01<\/strong><\/span><br \/>\n<a href=\"https:\/\/twitter.com\/HONjpNewsBlog?ref_src=twsrc%5Etfw\" class=\"twitter-follow-button\" data-size=\"large\" data-show-screen-name=\"false\" data-dnt=\"true\" data-show-count=\"false\">Follow @HONjpNewsBlog<\/a><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div>\n<p><span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:25829,&quot;href&quot;:&quot;https:\\\/\\\/www.watch.impress.co.jp\\\/docs\\\/news\\\/1314621.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251212222420\\\/https:\\\/\\\/www.watch.impress.co.jp\\\/docs\\\/news\\\/1314621.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:23:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-11 22:37:55&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 07:06:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-04 11:47:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:07:54&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 01:16:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 23:21:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:27:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:22:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-08 03:31:45&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-08 03:31:45&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25838,&quot;href&quot;:&quot;https:\\\/\\\/kachimai.jp\\\/article\\\/index.php?no=529384&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210326062723\\\/https:\\\/\\\/kachimai.jp\\\/article\\\/index.php?no=529384&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 21:00:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25839,&quot;href&quot;:&quot;https:\\\/\\\/prtimes.jp\\\/main\\\/html\\\/rd\\\/p\\\/000008361.000007006.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20230405023603\\\/https:\\\/\\\/prtimes.jp\\\/main\\\/html\\\/rd\\\/p\\\/000008361.000007006.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:20&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-21 08:53:24&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-13 22:14:55&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-23 02:12:16&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-09 13:33:03&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25831,&quot;href&quot;:&quot;https:\\\/\\\/contents.xj-storage.jp\\\/xcontents\\\/AS08114\\\/70082a8d\\\/0e10\\\/469b\\\/861a\\\/5bfcd3ea342d\\\/140120210325484839.pdf&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20240511152438\\\/https:\\\/\\\/contents.xj-storage.jp\\\/xcontents\\\/AS08114\\\/70082a8d\\\/0e10\\\/469b\\\/861a\\\/5bfcd3ea342d\\\/140120210325484839.pdf&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:24:49&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-11 22:37:55&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-21 07:06:29&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-04 11:47:41&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-13 22:07:54&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-23 01:16:16&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-27 21:00:51&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-09 13:27:02&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-25 03:22:48&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-15 12:47:21&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-06-15 12:47:21&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25840,&quot;href&quot;:&quot;https:\\\/\\\/www.trc.co.jp\\\/information\\\/pdf\\\/20210326_TRCrelease.pdf&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251206154010\\\/https:\\\/\\\/www.trc.co.jp\\\/information\\\/pdf\\\/20210326_TRCrelease.pdf&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:23&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-13 22:14:55&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-23 02:12:25&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25822,&quot;href&quot;:&quot;https:\\\/\\\/www.ndl.go.jp\\\/jp\\\/news\\\/fy2020\\\/210326_01.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250812030021\\\/https:\\\/\\\/www.ndl.go.jp\\\/jp\\\/news\\\/fy2020\\\/210326_01.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:22:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-11 22:37:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-19 07:56:40&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-04 11:47:39&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 22:07:54&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-23 01:16:32&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-27 21:00:38&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-09 13:27:00&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-25 03:22:49&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:22:49&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25841,&quot;href&quot;:&quot;https:\\\/\\\/www.ndl.go.jp\\\/jp\\\/data\\\/bib_newsletter\\\/2021_1\\\/article_01.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210326030838\\\/https:\\\/\\\/www.ndl.go.jp\\\/jp\\\/data\\\/bib_newsletter\\\/2021_1\\\/article_01.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:27&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-12 00:15:43&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-02-21 08:53:26&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-13 22:14:57&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-23 02:12:36&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-27 21:00:35&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-09 13:33:06&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-25 03:51:45&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:45&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25826,&quot;href&quot;:&quot;https:\\\/\\\/www.bunkanews.jp\\\/article\\\/230820&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251109032332\\\/https:\\\/\\\/www.bunkanews.jp\\\/article\\\/230820\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:23:21&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-02-11 22:37:55&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 07:06:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-04 11:47:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:07:55&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-23 01:16:11&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-27 23:21:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:26:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:22:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-08 03:31:49&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-08 03:31:49&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25842,&quot;href&quot;:&quot;https:\\\/\\\/www.hamakei.com\\\/headline\\\/11264&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251116121629\\\/https:\\\/\\\/www.hamakei.com\\\/headline\\\/11264\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:26&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:08&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25843,&quot;href&quot;:&quot;https:\\\/\\\/media-innovation.jp\\\/2021\\\/03\\\/25\\\/mi-subscription-1year-review&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20230203034145\\\/https:\\\/\\\/media-innovation.jp\\\/2021\\\/03\\\/25\\\/mi-subscription-1year-review\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:35&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:27&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-13 22:14:58&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 23:21:40&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25828,&quot;href&quot;:&quot;https:\\\/\\\/www.shinbunka.co.jp\\\/news2021\\\/03\\\/210325-04.htm&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20211019063339\\\/https:\\\/\\\/www.shinbunka.co.jp\\\/news2021\\\/03\\\/210325-04.htm&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:23:28&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-04 11:47:41&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 22:07:54&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-23 01:16:22&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-09 13:27:02&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-25 03:22:48&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-28 17:29:58&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-28 17:29:58&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25844,&quot;href&quot;:&quot;https:\\\/\\\/current.ndl.go.jp\\\/e2367&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251212132649\\\/https:\\\/\\\/current.ndl.go.jp\\\/e2367&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 21:00:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:03&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25845,&quot;href&quot;:&quot;https:\\\/\\\/current.ndl.go.jp\\\/e2366&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20250914154049\\\/https:\\\/\\\/current.ndl.go.jp\\\/e2366&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 21:00:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:45&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:45&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25846,&quot;href&quot;:&quot;https:\\\/\\\/note.com\\\/ume_nanminchamp\\\/n\\\/n90bc1bbc8809&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25847,&quot;href&quot;:&quot;https:\\\/\\\/current.ndl.go.jp\\\/ca1994&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251214193026\\\/https:\\\/\\\/current.ndl.go.jp\\\/ca1994&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:49&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:21&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 21:00:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25848,&quot;href&quot;:&quot;https:\\\/\\\/jp.techcrunch.com\\\/2021\\\/03\\\/25\\\/2021-03-23-facebooks-clubhouse-rival-looks-a-lot-like-clubhouse-right-now&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210926085311\\\/https:\\\/\\\/jp.techcrunch.com\\\/2021\\\/03\\\/25\\\/2021-03-23-facebooks-clubhouse-rival-looks-a-lot-like-clubhouse-right-now\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:51&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-12 00:15:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-21 08:53:24&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-13 22:14:55&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-23 02:12:13&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-27 21:00:47&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-09 13:33:02&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:46&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25849,&quot;href&quot;:&quot;https:\\\/\\\/www.publishersweekly.com\\\/pw\\\/by-topic\\\/industry-news\\\/comics\\\/article\\\/85890-prhps-will-distribute-marvel-comics-to-comics-stores.html&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251116025507\\\/https:\\\/\\\/www.publishersweekly.com\\\/pw\\\/by-topic\\\/industry-news\\\/comics\\\/article\\\/85890-prhps-will-distribute-marvel-comics-to-comics-stores.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:54&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:55&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25850,&quot;href&quot;:&quot;https:\\\/\\\/current.ndl.go.jp\\\/e2368&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20251219203815\\\/https:\\\/\\\/current.ndl.go.jp\\\/e2368&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 22:14:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 02:12:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25851,&quot;href&quot;:&quot;https:\\\/\\\/honjp-broadcasting-special202103.peatix.com\\\/view&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210311123701\\\/https:\\\/\\\/honjp-broadcasting-special202103.peatix.com\\\/view&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-15 05:45:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:26&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-25 00:06:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-03 20:23:14&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-08 00:35:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-12 05:18:28&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-15 08:57:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-20 22:43:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 05:37:53&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 08:12:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-06 21:31:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-10 01:16:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-07 03:07:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-12 01:57:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-26 22:54:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-30 14:37:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 21:13:39&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-19 12:15:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-23 21:15:07&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-27 02:01:42&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-01 20:32:31&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-05 16:31:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-09 15:16:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-13 15:08:34&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-13 15:08:34&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25837,&quot;href&quot;:&quot;https:\\\/\\\/honjp-broadcasting-33.peatix.com\\\/view&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210318113620\\\/https:\\\/\\\/honjp-broadcasting-33.peatix.com\\\/view&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:25:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-15 05:45:49&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-21 08:53:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-25 00:06:08&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-03 20:23:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-08 00:35:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-12 05:18:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-15 08:58:19&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-20 22:43:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 05:38:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-27 05:41:10&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 13:33:10&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-12 01:56:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-26 22:54:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-30 14:36:10&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-15 21:13:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-19 12:15:28&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-23 21:15:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-27 02:01:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-01 20:32:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-05 16:31:14&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-09 15:16:28&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-13 15:08:32&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-13 15:08:32&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25807,&quot;href&quot;:&quot;https:\\\/\\\/www.jbpa.or.jp\\\/pdf\\\/documents\\\/shinjin2021.pdf&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210317095454\\\/https:\\\/\\\/www.jbpa.or.jp\\\/pdf\\\/documents\\\/shinjin2021.pdf&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 11:19:18&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-25 00:06:10&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-04 15:04:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-08 00:35:25&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-11 21:09:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-15 10:49:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-20 22:43:12&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-24 05:37:49&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-27 05:41:17&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-06 21:31:45&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-10 01:17:04&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-07 03:07:36&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 01:57:30&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-26 22:54:23&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-01 13:35:30&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-15 21:13:37&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-19 12:15:41&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-23 21:15:11&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-27 02:01:51&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-01 20:32:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-05 16:31:09&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-09 15:16:26&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-13 15:08:36&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-13 15:08:36&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25729,&quot;href&quot;:&quot;https:\\\/\\\/honjp-newscasting-34.peatix.com\\\/view&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210323235030\\\/https:\\\/\\\/honjp-newscasting-34.peatix.com\\\/view&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 10:59:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-16 08:41:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-20 12:04:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-24 03:40:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-04 15:04:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-09 23:43:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-13 06:17:39&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-16 11:14:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-21 22:24:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 23:00:01&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-29 20:59:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-03 20:49:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 12:35:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-12 20:45:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-16 16:24:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-05 04:39:35&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-19 11:02:34&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-26 07:49:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-14 20:44:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-20 23:17:39&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-25 20:50:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-30 17:38:54&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-04 10:18:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-07 10:29:03&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-10 16:45:52&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-14 02:33:06&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-14 02:33:06&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25730,&quot;href&quot;:&quot;https:\\\/\\\/note.com\\\/events\\\/n\\\/n8a9f7bc17eb4&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25663,&quot;href&quot;:&quot;https:\\\/\\\/udbtalk01-202104.peatix.com&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210321075651\\\/https:\\\/\\\/udbtalk01-202104.peatix.com\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 10:43:28&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-12 00:15:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-15 11:06:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-19 04:24:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-22 11:18:06&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-02-25 22:18:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-04 15:04:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-08 00:35:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-11 11:11:38&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-14 19:52:04&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-18 12:03:28&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-21 22:24:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 23:00:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-03 00:34:47&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 12:35:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-12 20:45:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-30 04:48:37&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-05 04:39:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-09 13:48:27&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-19 11:03:07&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-25 11:58:03&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-14 20:44:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-19 12:15:39&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-24 21:15:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-27 22:36:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-01 17:22:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-05 04:50:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-09 15:16:31&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-12 21:32:44&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-12 21:32:44&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:25664,&quot;href&quot;:&quot;https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210314&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20210322095220\\\/https:\\\/\\\/www.jepa.or.jp\\\/seminar\\\/20210314\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-08 10:43:31&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-02-24 16:34:45&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-04 15:04:39&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-08 02:12:17&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-11 11:11:41&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-14 19:52:06&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-18 12:03:27&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-21 22:24:49&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-24 23:00:37&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-03-29 20:59:11&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-03 00:34:49&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-09 12:35:33&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-12 20:45:16&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-25 03:51:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-30 04:48:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-12 01:57:32&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-19 11:03:02&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-05-25 11:57:59&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-14 20:44:18&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-19 12:15:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-24 21:31:46&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-06-27 22:36:44&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-01 17:23:10&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-05 04:50:58&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-09 15:16:34&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-07-12 21:32:41&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-07-12 21:32:41&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:14854,&quot;href&quot;:&quot;https:\\\/\\\/twitter.com\\\/HONjpNewsBlog?ref_src=twsrc%5Etfw&quot;,&quot;archived_href&quot;:&quot;http:\\\/\\\/web-wp.archive.org\\\/web\\\/20230109190918\\\/https:\\\/\\\/twitter.com\\\/HONjpNewsBlog?ref_src=twsrc%5Etfw&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-02-06 23:31:26&quot;,&quot;http_code&quot;:400}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-02-06 23:31:26&quot;,&quot;http_code&quot;:400},&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>\u3000\u4f1d\u7d71\u7684\u306a\u53d6\u6b21\uff06\u66f8\u5e97\u6d41\u901a\u306e\u5546\u696d\u51fa\u7248\u304b\u3089\u3001\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u3092\u6d3b\u7528\u3057\u305f\u30c7\u30b8\u30bf\u30eb\u30d1\u30d6\u30ea\u30c3\u30b7\u30f3\u30b0\u307e\u3067\u3001\u5e83\u3044\u610f\u5473\u3067\u306e\u51fa\u7248\u306b\u95a2\u9023\u3059\u308b\u30cb\u30e5\u30fc\u30b9\u3092\u30c7\u30a4\u30ea\u30fc\u3067\u307e\u3068\u3081\u3066\u3044\u307e\u3059\u3002<\/p>\n<\/div>","protected":false},"author":9,"featured_media":30333,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAoiEM2xMfscec3m5-RpsRDKVy0:productID":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1992],"tags":[1841,2069,539,65,91,192,112,2117,397,214,227,1058,346,189,55,939,1822,152,615,884],"class_list":{"0":"post-30794","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-daily-news-summary","8":"tag-bookspro","9":"tag-clubhouse","10":"tag-dnp","11":"tag-facebook","12":"tag-jepa","13":"tag-jpro","14":"tag-kadokawa","15":"tag-nft","16":"tag-trc","17":"tag-twitter","18":"tag-227","19":"tag-1058","20":"tag-346","21":"tag-189","22":"tag-55","23":"tag-939","24":"tag-1822","25":"tag-152","26":"tag-615","27":"tag-884"},"jetpack_featured_media_url":"https:\/\/hon.jp\/news\/wp-content\/uploads\/2021\/01\/news-headline-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p71Ph0-80G","jetpack_sharing_enabled":true,"brizy_media":[],"_links":{"self":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/30794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/comments?post=30794"}],"version-history":[{"count":1,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/30794\/revisions"}],"predecessor-version":[{"id":30795,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/posts\/30794\/revisions\/30795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/media\/30333"}],"wp:attachment":[{"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/media?parent=30794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/categories?post=30794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hon.jp\/news\/wp-json\/wp\/v2\/tags?post=30794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}